{"id":88522,"date":"2026-02-26T10:50:49","date_gmt":"2026-02-26T10:50:49","guid":{"rendered":"https:\/\/www.lab.eus\/?p=88522"},"modified":"2026-02-27T09:11:46","modified_gmt":"2026-02-27T09:11:46","slug":"lab-se-ha-movilizado-ante-las-sedes-de-eudel-y-pnv-para-pedir-que-traigan-contenidos-a-la-mesa-del-convenio-udalhitz","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/lab-se-ha-movilizado-ante-las-sedes-de-eudel-y-pnv-para-pedir-que-traigan-contenidos-a-la-mesa-del-convenio-udalhitz\/","title":{"rendered":"LAB se ha movilizado ante las sedes de EUDEL y PNV para pedir que traigan contenidos a la mesa del convenio Udalhitz"},"content":{"rendered":"\n<p><strong>LAB pide a EUDEL y al PNV, que ostenta su presidencia, que \u00abrompan con el bloqueo existente desde el 7 de noviembre y traigan a las mesas contenidos suficientes para negociar\u00bb<\/strong>.<\/p>\n\n\n\n<p>El de hoy ha sido el primer paso de la din\u00e1mica de movilizaciones que ha emprendido el sindicato LAB ante la situaci\u00f3n de bloqueo que vive la negociaci\u00f3n de Udalhitz. De hecho, LAB decidi\u00f3 iniciar las movilizaciones porque no hab\u00eda habido avances desde que el pasado 7 de noviembre. EUDEL y el PNV, que ostenta la presidencia, han mantenido la mesa bloqueada, y ya ha pasado a\u00f1o y medio desde que se inici\u00f3 la negociaci\u00f3n con continuas dilaciones. LAB ha recordado que se cumplen 16 a\u00f1os de la firma del convenio colectivo de Udalhitz y desde entonces no se ha producido la renovaci\u00f3n del mismo.<\/p>\n\n\n\n<p>Como ha se\u00f1alado el sindicato, en este largo a\u00f1o y medio han sido pocos los avances que ha habido. La constituci\u00f3n de la mesa negociadora fue en abril de 2025 y tras cinco reuniones, desde el 7 de noviembre la mesa negociadora ha estado bloqueada. Sin nuevas convocatorias ni propuestas.<\/p>\n\n\n\n<p>As\u00ed las cosas, en la \u00faltima reuni\u00f3n, LAB solicit\u00f3 a EUDEL que actuara con responsabilidad y altura de miras hacia las personas trabajadoras y enviara y llevara a la mesa el borrador de acuerdo integral para el nuevo Udalhitz.<\/p>\n\n\n\n<p>Por fin, para ma\u00f1ana, 27 de febrero, LAB ha recibido la pr\u00f3xima convocatoria de la mesa negociadora de Udalhitz. LAB considera que las propuestas que ha presentado EUDEL para esta mesa son muy generales y est\u00e1 por ver si los partidos pol\u00edticos presentan voluntad real de negociar. La de hoy ha sido tambi\u00e9n una movilizaci\u00f3n para exigir esa voluntad, para que no se pierda m\u00e1s tiempo en las reuniones.<\/p>\n\n\n\n<p>Por lo tanto, LAB exige que haya contenidos sobre la mesa y si no hay voluntad negociadora y contenidos concretos no descartar\u00e1 que se intensifiquen las movilizaciones y se convoquen huelgas. No va a permitir m\u00e1s moratorias despu\u00e9s de 4 meses sin avances.<\/p>\n\n\n\n<p><strong>Los contenidos prioritarios por los que luchar\u00e1 el sindicato LAB para el nuevo Udalhitz son los siguientes:&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Marco de negociaci\u00f3n propio. La urgencia de decidir aqu\u00ed, superando las imposiciones del Estado.<\/li>\n\n\n\n<li>Paralizaci\u00f3n de privatizaciones y realizaci\u00f3n de publificaciones. Desarrollar la gesti\u00f3n p\u00fablica propia de los servicios que dan los ayuntamientos y promover las publificaciones.<\/li>\n\n\n\n<li>Medidas relacionadas con el empleo. Reducci\u00f3n de la temporalidad, creaci\u00f3n de empleo, jornadas al 100% en sectores feminizados y convocatorias de selecci\u00f3n propias y de traslados.&nbsp;<\/li>\n\n\n\n<li>Planes de rejuvenecimiento. Obligatoriedad de que todos los ayuntamientos dispongan de planes de recursos humanos que contemplen planes de rejuvenecimiento. Acordar reducciones de jornada por edad sin p\u00e9rdida de salario ni de cotizaci\u00f3n y percibir el derecho a que dichas reducciones de jornada sean acumuladas. Garantizar los contratos de relevo para el personal laboral.<\/li>\n\n\n\n<li>Reducci\u00f3n de la jornada laboral. Reducci\u00f3n de la semana laboral a 30 horas. Reducci\u00f3n de jornada y horas lectivas en las Escuelas Municipales de M\u00fasica y Euskaltegis.<\/li>\n\n\n\n<li>Realizaci\u00f3n de valoraciones de puestos de trabajo: Realizar valoraciones de puestos de trabajo para reducir la brecha entre categor\u00edas laborales.<\/li>\n\n\n\n<li>Incrementos salariales. Recuperar el poder adquisitivo perdido ante el encarecimiento de la vida. Acordar f\u00f3rmulas para realizar incrementos salariales con garant\u00edas jur\u00eddicas. Que los incrementos salariales sean lineales. Y que ninguna persona trabajadora subcontratada tenga un salario m\u00ednimo por debajo de los 1.500 \u20ac con 14 pagas.<\/li>\n\n\n\n<li>Cl\u00e1usulas feministas. Medidas para reactivar los planes de igualdad. Medidas para acabar con la brecha salarial. Eficacia de los protocolos de acoso. Consensuar protocolos contra la LGTBIfobia. Establecer medidas concretas para revertir la situaci\u00f3n en los colectivos masculinizados para llevar a cabo la contrataci\u00f3n de mujeres*. Ampliar los permisos de conciliaci\u00f3n a trav\u00e9s de vinculogramas que superen el v\u00ednculo familiar y m\u00e1s permisos vinculados al cuidado.<\/li>\n\n\n\n<li>Medidas para la normalizaci\u00f3n del euskera. Consensuar instrumentos con seguridad jur\u00eddica para equiparar el euskera y el castellano en los puestos de trabajo, estableciendo el requisito de que todos los puestos sean biling\u00fces. Garantizar los derechos del euskera como lengua de trabajo y de atenci\u00f3n. La primera vez que se acceda al puesto, las dos lenguas oficiales deben ser obligatorias. Planes de euskaldunizaci\u00f3n para el personal actualmente en activo, con plazos concretos y recursos. Que todos los puestos de trabajo tengan perfil ling\u00fc\u00edstico pasados los 12 a\u00f1os.<\/li>\n\n\n\n<li>Medidas de salud laboral. Gesti\u00f3n por parte de la Seguridad Social de las contingencias profesionales. Abono del 100% de las bajas hasta su finalizaci\u00f3n. Realizaci\u00f3n de evaluaciones de riesgos psiocosociales y medidas para evitarlos. Acordar medidas para aliviar las cargas de trabajo.<\/li>\n\n\n\n<li>Medidas para la transici\u00f3n ecosocial. Establecer planes consensuados de movilidad de forma prioritaria.<\/li>\n\n\n\n<li>Acordar medidas concretas en colectivos espec\u00edficos. Establecimiento de medidas de mejora de las condiciones de trabajo, reducci\u00f3n de jornada y cargas de trabajo para Euskaltegis, Escuelas de M\u00fasica y Centros de Formaci\u00f3n Profesional B\u00e1sica.<\/li>\n<\/ul>\n\n\n\n<p>Por lo tanto, hoy LAB hace un llamamiento a la voluntad negociadora en la mesa de Udalhitz y a trabajar los consensos en los contenidos mencionados. Y en funci\u00f3n de lo que suceda ma\u00f1ana y de los contenidos que haya en la mesa anunciar\u00e1 si intensifica las movilizaciones.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAB pide a EUDEL y al PNV, que ostenta su presidencia, que \u00abrompan con el bloqueo existente desde el 7 de noviembre y traigan a las mesas contenidos suficientes para negociar\u00bb. El de hoy ha sido el primer paso de la din\u00e1mica de movilizaciones que ha emprendido el sindicato LAB ante la situaci\u00f3n de bloqueo [&hellip;]<\/p>\n","protected":false},"author":1191,"featured_media":88519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18,3108,2867,6],"tags":[3033,3450,3178,1209,3066,3171,1499],"class_list":{"0":"post-88522","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"category-administracion-municipal-y-foral","9":"category-federaciones","10":"category-es-servicios-publicos","11":"tag-accion-sindical-es","12":"tag-administracion-local-y-foral","13":"tag-destacado-1","14":"tag-eudel","15":"tag-federaciones-es","16":"tag-servicios-publicos-es","17":"tag-udalhitz"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=88522"}],"version-history":[{"count":3,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88522\/revisions"}],"predecessor-version":[{"id":88579,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88522\/revisions\/88579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/88519"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=88522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=88522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=88522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}