{"id":88514,"date":"2026-02-26T08:22:52","date_gmt":"2026-02-26T08:22:52","guid":{"rendered":"https:\/\/www.lab.eus\/?p=88514"},"modified":"2026-02-26T08:22:56","modified_gmt":"2026-02-26T08:22:56","slug":"la-sentencia-ganada-en-los-juzgados-por-el-comite-de-empresa-de-kybse-en-ororbia-ha-sido-un-trabajo-colectivo","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/la-sentencia-ganada-en-los-juzgados-por-el-comite-de-empresa-de-kybse-en-ororbia-ha-sido-un-trabajo-colectivo\/","title":{"rendered":"La sentencia ganada en los juzgados por el comit\u00e9 de empresa de KYBSE en Ororbia ha sido un trabajo colectivo"},"content":{"rendered":"\n<p>La representaci\u00f3n de los sindicatos LAB, ELA, UGT Y CC de KYBSE en Ororbia queremos aclarar las informaciones aparecidas en prensa el d\u00eda 3 de febrero, en las que el sindicato CCOO present\u00f3 la sentencia ganada en los juzgados por el comit\u00e9 de empresa como una victoria sindical unilateral, cuando en realidad ha sido un trabajo colectivo.<\/p>\n\n\n\n<p>El comit\u00e9 de empresa tiene como f\u00f3rmula de trabajo el reparto rotatorio de interponer denuncias colectivas por unanimidad en defensa de la plantilla, siendo un mecanismo de equidad y reparto del trabajo sindical con los diferentes servicios jur\u00eddicos de los sindicatos con representaci\u00f3n en nuestro comit\u00e9.<\/p>\n\n\n\n<p>Siempre se han respetado los logros y victorias judiciales sin apropiarse del trabajo colectivo realizado por todas las secciones sindicales, sin hacerlas p\u00fablicas para apuntarse tantos de trabajo colectivo. Los firmantes queremos mostrar nuestro desagrado con estas formas de actuar siendo una clara falta de respeto a las m\u00e1s de 750 personas de la plantilla de la f\u00e1brica.<\/p>\n\n\n\n<p>Dicho esto, queremos valorar positivamente la victoria en los juzgados de la demanda colectiva en la que la empresa es condenada por no cumplir en tiempo y vol\u00famenes la puesta en marcha de una l\u00ednea de montaje en la f\u00e1brica de Ororbia.<\/p>\n\n\n\n<p>Queremos lanzar un mensaje claro a la multinacional: el convenio est\u00e1 para cumplirse. Y cuando no se cumple la lucha sindical es fundamental para controlar la actuaci\u00f3n de la direcci\u00f3n, la carga de trabajo para la planta y defender nuestros derechos laborales.<\/p>\n\n\n\n<p>La sentencia que va ser recurrida por la empresa es un claro mensaje que tiene que hacer reflexionar a la parte empresarial: los acuerdos son de obligado cumplimiento, de no ser as\u00ed la clase trabajadora debemos ser exigentes en la defensa de nuestro convenio colectivo, siendo la v\u00eda judicial otra herramienta m\u00e1s para hacer valer nuestros derechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La representaci\u00f3n de los sindicatos LAB, ELA, UGT Y CC de KYBSE en Ororbia queremos aclarar las informaciones aparecidas en prensa el d\u00eda 3 de febrero, en las que el sindicato CCOO present\u00f3 la sentencia ganada en los juzgados por el comit\u00e9 de empresa como una victoria sindical unilateral, cuando en realidad ha sido un [&hellip;]<\/p>\n","protected":false},"author":1191,"featured_media":88512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18,2867,2868],"tags":[3033,3178,3066,2996,2358,5406],"class_list":{"0":"post-88514","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"category-federaciones","9":"category-industria-es","10":"tag-accion-sindical-es","11":"tag-destacado-1","12":"tag-federaciones-es","13":"tag-industria-es","14":"tag-kybse","15":"tag-kybse-ororbia"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=88514"}],"version-history":[{"count":1,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88514\/revisions"}],"predecessor-version":[{"id":88515,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88514\/revisions\/88515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/88512"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=88514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=88514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=88514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}