{"id":88467,"date":"2026-02-25T12:32:41","date_gmt":"2026-02-25T12:32:41","guid":{"rendered":"https:\/\/www.lab.eus\/?p=88467"},"modified":"2026-02-25T12:32:44","modified_gmt":"2026-02-25T12:32:44","slug":"intervencion-social-en-bizkaia-tres-debates-urgentes-para-salvar-el-sector","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/intervencion-social-en-bizkaia-tres-debates-urgentes-para-salvar-el-sector\/","title":{"rendered":"Intervenci\u00f3n social en Bizkaia: tres debates urgentes para salvar el sector"},"content":{"rendered":"\n<p>En el marco de la mesa de negociaci\u00f3n de intervenci\u00f3n social de Bizkaia, planteamos tres debates fundamentales, interrelacionados e indivisibles, cuyo objetivo es garantizar la calidad del servicio p\u00fablico y el futuro del sector.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">1. Un modelo agotado que necesita una transformaci\u00f3n estructural<\/h2>\n\n\n\n<p>El actual modelo de intervenci\u00f3n social est\u00e1 agotado. Presenta graves deficiencias estructurales en su modelo y su financiaci\u00f3n. Sobrevivir no es una soluci\u00f3n.<\/p>\n\n\n\n<p>El modelo actual no garantiza un servicio de calidad. Agota a las personas trabajadoras, tensiona a los equipos y repercute negativamente en la atenci\u00f3n a las personas usuarias.<\/p>\n\n\n\n<p>Desde nuestra responsabilidad sindical consideramos imprescindible abrir un proceso de trabajo conjunto que permita avanzar hacia un nuevo modelo que d\u00e9 respuestas integrales.<\/p>\n\n\n\n<p>En la pr\u00e1ctica, las entidades act\u00faan como ejecutoras de decisiones pol\u00edticas tomadas por las administraciones p\u00fablicas, sin atender a criterios o necesidades t\u00e9cnicas. Este sistema no sirve ni a las trabajadoras, ni a las entidades, ni a la ciudadan\u00eda. A las entidades les decimos que sobrevivir como entidad no es la soluci\u00f3n.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">2. Hacia un modelo p\u00fablico de gesti\u00f3n p\u00fablica<\/h2>\n\n\n\n<p>El cambio de modelo debe ir acompa\u00f1ado del reconocimiento del trabajo p\u00fablico que realiza el sector.<\/p>\n\n\n\n<p>No hablamos \u00fanicamente de reconocer que se cumple una funci\u00f3n p\u00fablica dentro de un modelo de gesti\u00f3n privada. Hablamos de avanzar hacia un modelo plenamente p\u00fablico, donde la gesti\u00f3n y la capacidad de decisi\u00f3n tambi\u00e9n sean p\u00fablicas.<\/p>\n\n\n\n<p>Ser p\u00fablico, por s\u00ed solo, no garantiza autom\u00e1ticamente mejores resultados. Sin embargo, un cambio estructural que sit\u00fae al sector en un marco de gesti\u00f3n p\u00fablica permitir\u00eda fortalecer su estabilidad, calidad y coherencia.<\/p>\n\n\n\n<p>La publificaci\u00f3n se perfila como horizonte de futuro, y la equiparaci\u00f3n como herramienta para avanzar en ese camino. Las trabajadoras del sector han comenzado a identificar esta v\u00eda como una posible salida a la crisis del modelo actual. Es el momento de que las entidades definan tambi\u00e9n su posicionamiento estrat\u00e9gico.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">3. Medidas concretas para mejorar las condiciones del sector<\/h2>\n\n\n\n<p>En la anterior negociaci\u00f3n se abordaron debates intensos pero necesarios, como la implementaci\u00f3n de medidas contra los riesgos psicosociales o la regulaci\u00f3n de las incapacidades temporales, recuperaci\u00f3n del poder adquisitivo, limitar la parcialidad, limitar el uso de las modificaciones sustanciales, reducciones de jornada sin reducci\u00f3n salarial para trabajadoras de 60 a\u00f1os, etc.<\/p>\n\n\n\n<p>Estas medidas no solo significaron avances para las personas trabajadoras, adem\u00e1s permitieron abrir debates necesarios que pon\u00edan en cuesti\u00f3n el modelo actual.<\/p>\n\n\n\n<p>Consideramos que es imprescindible afrontar esos debates, incorporando medidas concretas que mejoren las condiciones laborales y refuercen la calidad del servicio.<\/p>\n\n\n\n<p>Por ello plantearemos en la mesa de negociaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Medidas que establezcan la obligaci\u00f3n de la pareja educativa en m\u00e1s servicios e intervenciones.<\/li>\n\n\n\n<li>Una propuesta de ratios para los centros de menores que abra el camino a una propuesta de ratio para el resto de servicios.<\/li>\n\n\n\n<li>Equiparaci\u00f3n salarial con las trabajadoras p\u00fablicas.<\/li>\n\n\n\n<li>Medidas contra la precariedad.<\/li>\n\n\n\n<li>Medidas de conciliaci\u00f3n, como flexibilidad horaria, tiempo indefinido para acompa\u00f1amiento a consultas, vinculograma, entre otras.<\/li>\n\n\n\n<li>Medidas concretas para impulsar la euskaldunizaci\u00f3n del sector.<\/li>\n\n\n\n<li>Medidas para afrontar la \u00faltima etapa de la vida laboral: reducciones del 40% sin reducci\u00f3n salarial y contrato relevo.<\/li>\n<\/ul>\n\n\n\n<p>El sector de la intervenci\u00f3n social en Bizkaia necesita decisiones valientes y estructurales. Abrir estos tres debates no es una opci\u00f3n, sino una responsabilidad colectiva para garantizar un servicio p\u00fablico de calidad y un futuro digno para quienes lo sostienen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la mesa de negociaci\u00f3n de intervenci\u00f3n social de Bizkaia, planteamos tres debates fundamentales, interrelacionados e indivisibles, cuyo objetivo es garantizar la calidad del servicio p\u00fablico y el futuro del sector. 1. Un modelo agotado que necesita una transformaci\u00f3n estructural El actual modelo de intervenci\u00f3n social est\u00e1 agotado. Presenta graves deficiencias estructurales [&hellip;]<\/p>\n","protected":false},"author":1191,"featured_media":88465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18],"tags":[3033,3178],"class_list":{"0":"post-88467","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"tag-accion-sindical-es","9":"tag-destacado-1"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=88467"}],"version-history":[{"count":1,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88467\/revisions"}],"predecessor-version":[{"id":88468,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88467\/revisions\/88468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/88465"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=88467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=88467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=88467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}