{"id":88381,"date":"2026-02-24T13:50:46","date_gmt":"2026-02-24T13:50:46","guid":{"rendered":"https:\/\/www.lab.eus\/?p=88381"},"modified":"2026-02-24T13:50:49","modified_gmt":"2026-02-24T13:50:49","slug":"seguimiento-masivo-en-la-primera-jornada-de-huelga-de-comedores-escolares-de-la-cav-en-defensa-de-unas-condiciones-laborales-dignas","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/seguimiento-masivo-en-la-primera-jornada-de-huelga-de-comedores-escolares-de-la-cav-en-defensa-de-unas-condiciones-laborales-dignas\/","title":{"rendered":"Seguimiento masivo en la primera jornada de huelga de comedores escolares de la CAV en defensa de unas condiciones laborales dignas"},"content":{"rendered":"\n<p><strong>Hoy las trabajadoras de los comedores escolares de gesti\u00f3n directa de las escuelas p\u00fablicas de la CAV han protagonizado una movilizaci\u00f3n masiva en defensa de sus derechos laborales. Los sindicatos LAB, ELA, CCOO y UGT han destacado el alto seguimiento de la huelga, subrayando la unidad, organizaci\u00f3n y fuerza colectiva demostrada, a pesar de unos servicios m\u00ednimos abusivos y desproporcionados.\u00a0<\/strong><\/p>\n\n\n\n<p>Reivindican condiciones laborales dignas y el reconocimiento como parte fundamental de la comunidad educativa, ya que su labor no solo consiste en servir comida, sino tambi\u00e9n en educar, acompa\u00f1ar y cuidar al alumnado. Denuncian presiones por parte de las empresas para frenar la movilizaci\u00f3n, pero afirman que no han logrado dividirlas.<\/p>\n\n\n\n<p>Sus principales demandas son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El cumplimiento del convenio y el pago \u00edntegro de las subidas salariales, con equiparaci\u00f3n al personal del Gobierno Vasco.<\/li>\n\n\n\n<li>Una negociaci\u00f3n real y con contenidos concretos.<\/li>\n\n\n\n<li>La apertura de un proceso de dialago con el Departamento de Educaci\u00f3n para modificar la normativa de comedores, abordando ratios, funciones y jornadas.<\/li>\n<\/ul>\n\n\n\n<p>Critican que la patronal quiera limitar la subida salarial al 0,5% y rechazan cualquier interpretaci\u00f3n que incumpla la equiparaci\u00f3n salarial acordada. Denuncian tambi\u00e9n la precariedad del sector: jornadas parciales, contratos precarios y falta de reconocimiento de sus responsabilidades educativas.<\/p>\n\n\n\n<p>Hacen un llamamiento al conjunto de la comunidad educativay para defender un comedor escolar p\u00fablico y de calidad, se\u00f1alando que la precarizaci\u00f3n laboral afecta directamente al servicio que recibe el alumnado.<\/p>\n\n\n\n<p>Anuncian que las movilizaciones continuar\u00e1n si no hay respuestas ni negociaci\u00f3n real, y enmarcan esta lucha no solo como una reivindicaci\u00f3n econ\u00f3mica, sino como una cuesti\u00f3n de dignidad, reconocimiento y respeto.<\/p>\n\n\n\n<p>Concluyen reafirmando su determinaci\u00f3n de no retroceder y continuar organizadas en defensa de unas condiciones laborales dignas.<\/p>\n\n\n\n<p>Ma\u00f1ana, 25 de febrero seguiran movilizandose en las delegaciones territoriales del Gobierno Vasco de Araba, Bizkaia y Gipuzkoa.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy las trabajadoras de los comedores escolares de gesti\u00f3n directa de las escuelas p\u00fablicas de la CAV han protagonizado una movilizaci\u00f3n masiva en defensa de sus derechos laborales. Los sindicatos LAB, ELA, CCOO y UGT han destacado el alto seguimiento de la huelga, subrayando la unidad, organizaci\u00f3n y fuerza colectiva demostrada, a pesar de unos [&hellip;]<\/p>\n","protected":false},"author":1191,"featured_media":88379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18],"tags":[3033,3178],"class_list":{"0":"post-88381","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"tag-accion-sindical-es","9":"tag-destacado-1"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=88381"}],"version-history":[{"count":1,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88381\/revisions"}],"predecessor-version":[{"id":88382,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88381\/revisions\/88382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/88379"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=88381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=88381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=88381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}