{"id":88278,"date":"2026-02-20T13:19:34","date_gmt":"2026-02-20T13:19:34","guid":{"rendered":"https:\/\/www.lab.eus\/?p=88278"},"modified":"2026-02-20T13:19:38","modified_gmt":"2026-02-20T13:19:38","slug":"lab-quiere-denunciar-los-ataques-contra-las-personas-trabajadoras-euskaldunes-por-parte-del-departamento-de-educacion","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/lab-quiere-denunciar-los-ataques-contra-las-personas-trabajadoras-euskaldunes-por-parte-del-departamento-de-educacion\/","title":{"rendered":"LAB quiere denunciar los ataques contra las personas trabajadoras euskaldunes por parte del Departamento de Educaci\u00f3n"},"content":{"rendered":"\n<p><strong>\u00abSer euskaldun se sit\u00faa una y otra vez por detr\u00e1s de no serlo\u00bb<\/strong><\/p>\n\n\n\n<p>Desde el inicio del curso, LAB ha denunciado reiteradamente los ataques contra las personas trabajadoras euskaldunes. El primer ejemplo se produjo en el proceso abierto por el Departamento de Educaci\u00f3n el 17 de diciembre de cara al concurso de traslados. En \u00e9l se public\u00f3 una resoluci\u00f3n que permit\u00eda no ofertar los puestos de trabajo con perfil ling\u00fc\u00edstico 1 (nivel B2).<\/p>\n\n\n\n<p>En este sentido, adem\u00e1s de la posibilidad de no ofertar todos los puestos recogidos en la Relaci\u00f3n de Puestos de Trabajo, el Departamento dio paso a una medida discriminatoria hacia el personal funcionario de carrera con perfil ling\u00fc\u00edstico 2 (nivel C1). De hecho, dichos puestos podr\u00e1n asignarse prioritariamente a personal que no tenga el perfil ling\u00fc\u00edstico necesario para impartir clases en euskera.<\/p>\n\n\n\n<p>Con anterioridad, en la orden que regula el proceso de adjudicaci\u00f3n de plazas al inicio del curso, el Departamento estableci\u00f3 que el personal con perfil ling\u00fc\u00edstico 2 solo pod\u00eda solicitar y obtener plazas con perfil 2. La norma recog\u00eda como excepci\u00f3n que el personal con el perfil 2 acreditado solo pod\u00eda acceder a plazas de perfil 1 siempre que ello no impidiera que el personal con \u00fanicamente perfil 1 obtuviera dichas plazas, aunque este \u00faltimo tuviera menor puntuaci\u00f3n. Todo ello vulnerando completamente la antig\u00fcedad y los derechos del personal p\u00fablico.<\/p>\n\n\n\n<p>Con el apoyo de LAB, varias personas trabajadoras en esta situaci\u00f3n han iniciado la v\u00eda jur\u00eddica y se les ha reconocido la vulneraci\u00f3n. Por ello, desde LAB exigimos que el Departamento de Educaci\u00f3n retire de manera general la cl\u00e1usula establecida en la orden y que trate a todo el personal por igual, sin dar pasos atr\u00e1s en el proceso de euskaldunizaci\u00f3n.<\/p>\n\n\n\n<p>Desde LAB denunciamos que el Departamento mantiene situaciones discriminatorias hacia el personal con segundo perfil ling\u00fc\u00edstico. Por un lado, aunque los estudios se ofrezcan en euskera y en modelo D, se empuja al profesorado a impartir las clases en castellano; y por otro, en el concurso de traslados, en lugar de ofertar todos los puestos a todo el personal con transparencia e igualdad de oportunidades, public\u00f3 una resoluci\u00f3n que permit\u00eda no ofertar las plazas con perfil ling\u00fc\u00edstico 1, dando paso a una medida discriminatoria hacia el resto del personal.<\/p>\n\n\n\n<p>Seg\u00fan los datos de LAB, los puestos sin perfil ling\u00fc\u00edstico ni fecha de preceptividad son los siguientes: en Formaci\u00f3n Profesional, 1.305 puestos con perfil ling\u00fc\u00edstico 1 (mientras que 2.696 tienen perfil 2); y en Educaci\u00f3n Secundaria e ense\u00f1anzas integradas, 222 puestos con perfil 1 (frente a 6.804 con perfil 2).<\/p>\n\n\n\n<p>Muchos puestos de Formaci\u00f3n Profesional y de Educaci\u00f3n Secundaria Obligatoria no tienen perfil ling\u00fc\u00edstico ni fecha de preceptividad. Adem\u00e1s, es necesario un plan eficaz para la euskaldunizaci\u00f3n del personal de servicios y superar los modelos ling\u00fc\u00edsticos que no euskaldunizan para garantizar el derecho del alumnado a estudiar en euskera.&nbsp;<\/p>\n\n\n\n<p>Las vulneraciones no se limitan \u00fanicamente al personal trabajador: mediante la oferta de modelos que no euskaldunizan, se niega a muchos alumnos y alumnas el derecho a estudiar en euskera y la posibilidad de conocer la cultura vasca. De todos los ciclos ofrecidos a trav\u00e9s de modelos que no euskaldunizan, solo el 60% se imparte en euskera en \u00c1lava, Bizkaia y Gipuzkoa. Esta situaci\u00f3n se agrava en la Formaci\u00f3n Profesional B\u00e1sica, donde el modelo D es anecd\u00f3tico (18,5% de las matr\u00edculas).<\/p>\n\n\n\n<p>Por tanto, adem\u00e1s de exigir que todos los puestos tengan perfil ling\u00fc\u00edstico y fecha de preceptividad establecida, LAB reivindica que es imprescindible desarrollar los planes de euskera recogidos en los convenios colectivos firmados para euskaldunizar a todo el personal p\u00fablico, as\u00ed como ofrecer a todo el personal de todos los colectivos la posibilidad de participar en cursos para mantener y mejorar su nivel de euskera.&nbsp;<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSer euskaldun se sit\u00faa una y otra vez por detr\u00e1s de no serlo\u00bb Desde el inicio del curso, LAB ha denunciado reiteradamente los ataques contra las personas trabajadoras euskaldunes. El primer ejemplo se produjo en el proceso abierto por el Departamento de Educaci\u00f3n el 17 de diciembre de cara al concurso de traslados. En \u00e9l [&hellip;]<\/p>\n","protected":false},"author":1191,"featured_media":79735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18,33,6],"tags":[3033,3178,3194,3171],"class_list":{"0":"post-88278","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"category-es-ensenanza","9":"category-es-servicios-publicos","10":"tag-accion-sindical-es","11":"tag-destacado-1","12":"tag-ensenanza-es","13":"tag-servicios-publicos-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=88278"}],"version-history":[{"count":1,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88278\/revisions"}],"predecessor-version":[{"id":88279,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88278\/revisions\/88279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/79735"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=88278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=88278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=88278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}