{"id":88215,"date":"2026-02-19T11:56:17","date_gmt":"2026-02-19T11:56:17","guid":{"rendered":"https:\/\/www.lab.eus\/?p=88215"},"modified":"2026-03-16T09:05:55","modified_gmt":"2026-03-16T09:05:55","slug":"opinion-pagar-multas-no-es-cumplir-con-la-legislacion-vigente","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/opinion-pagar-multas-no-es-cumplir-con-la-legislacion-vigente\/","title":{"rendered":"[OPINI\u00d3N]: Pagar multas no es cumplir con la legislaci\u00f3n vigente"},"content":{"rendered":"\n<p><strong>Ra\u00fal Portillo Alzueta, Secretario General de la Secci\u00f3n Sindical de LAB en VW Navarra, y miembro del Comit\u00e9 de Empresa de VW Navarra<\/strong>.<\/p>\n\n\n\n<p>La Direcci\u00f3n de VW Navarra habitualmente emplea a los medios de comunicaci\u00f3n como herramienta de presi\u00f3n medi\u00e1tica, propaganda y desinformaci\u00f3n, mentir no es informar.<\/p>\n\n\n\n<p>Recientemente VW publicaba a los 4 vientos: <em>\u201cEn VW reforzaremos a\u00fan m\u00e1s nuestras pr\u00e1cticas de contrataci\u00f3n, garantizando en todo momento la m\u00e1xima transparencia y el estricto cumplimiento de la legislaci\u00f3n vigente\u201d.<\/em><\/p>\n\n\n\n<p>Todo el mundo conoce la corrupci\u00f3n que existe en torno al empleo en VW Navarra, alardear de transparencia, cuando niegan al Comit\u00e9 de Empresa el acceso a las bolsas de empleo que ellos y sus secuaces manejan, cuando se negaron a acordar un Acuerdo de empleo p\u00fablico, transparente, verificable y supervisado por el Comit\u00e9 de Empresa, es como poco mezquino.<\/p>\n\n\n\n<p>La nota segu\u00eda diciendo: \u201c<em>Nuestro compromiso con el empleo estable y de calidad en Navarra ha sido y seguir\u00e1 siendo un pilar fundamental de nuestra forma de trabajar<\/em>\u201d.<\/p>\n\n\n\n<p>Tal vez por eso hace m\u00e1s de 2 a\u00f1os que firmaron junto a UGT y CCOO un excedente de 400 personas, y tal vez por eso los mismos actores acordaron hace algunos a\u00f1os m\u00e1s, rebajar el salario a los trabajadores y trabajadoras de nuevo ingreso un 26% durante el primer a\u00f1o de contrato y un 15% los 3 a\u00f1os siguientes.<\/p>\n\n\n\n<p>A esta forma de actuar VW, UGT y CCOO le llaman \u201cempleo estable y de calidad\u201d, acordando excedentes de plantilla y empeorando las condiciones econ\u00f3micas de la plantilla m\u00e1s vulnerable, la eventual.<\/p>\n\n\n\n<p>VW Navarra no cumple por motu proprio la legislaci\u00f3n vigente, desde LAB llevamos a\u00f1os oblig\u00e1ndole a cumplirla a base de denuncias en la Inspecci\u00f3n de Trabajo.<\/p>\n\n\n\n<p>VW acord\u00f3 un Plan de Igualdad en 2023 despu\u00e9s de recibir 3 resoluciones de la Inspecci\u00f3n inst\u00e1ndole a ello, el pasado a\u00f1o acord\u00f3 una nueva organizaci\u00f3n del Servicio Contraincendios, despu\u00e9s de que Inspecci\u00f3n le dijera que estaba incumpliendo el anterior.<\/p>\n\n\n\n<p>La copia b\u00e1sica de los contratos las empezamos a recibir en 2017, tras m\u00faltiples denuncias de LAB, hasta entonces VW ignoraba el art\u00edculo 8 del Estatuto de los Trabajadores, otra muestra de \u201ctransparencia\u201d.<\/p>\n\n\n\n<p>VW cuenta en su contra con m\u00faltiples resoluciones por contrataci\u00f3n en fraude de ley, en 2011 fueron m\u00e1s de 1000 los contratos fraudulentos.<\/p>\n\n\n\n<p>Por no hablar de resoluciones por cesi\u00f3n ilegal de trabajadores, por vulneraci\u00f3n del derecho de huelga, por horas extraordinarias nocturnas, por no haber pasado 12 horas de descanso entre turnos, por abuso del contrato en pr\u00e1cticas, por no pagar pluses estando de permiso retribuido, \u2026de las innumerables denuncias de salud laboral no vamos a comentar nada.<\/p>\n\n\n\n<p>A esto lo llaman \u201cestricto cumplimiento de la legislaci\u00f3n vigente\u201d, normalmente la situaci\u00f3n se resuelve abonando multas, que por pronto pago son rid\u00edculas para una multinacional como VW.<\/p>\n\n\n\n<p>Otros se limitan a controlar f\u00e9rreamente su cortijo, dicen velar por la plantilla eventual cuando ellos son los que les han mermado el salario, los que les presionan para que no se cojan la baja ni denuncien su situaci\u00f3n.<\/p>\n\n\n\n<p>Ahora VW, UGT, CCOO han firmado un acuerdo por el cual van a contratar a 400 personas en el mismo intervalo de tiempo en que acordaron enviar al ERTE, seg\u00fan el d\u00eda de la semana, entre 1000 y 2000 personas, a eso se le llama hacer negocio con el empleo, su negocio.<\/p>\n\n\n\n<p>Desde LAB velaremos porque todo este proceso se ajuste a la legalidad, de no ser as\u00ed, los \u00fanicos responsables de lo que pueda ocurrir son los firmantes de este acuerdo.<\/p>\n\n\n\n<p>Usar a la opini\u00f3n p\u00fablica para tratar de ocultar tus infracciones en materia laboral, tratando de presionar a los que denunciamos las mismas, creando un conflicto laboral ficticio, para luego presentarte como el salvador del mundo ante la opini\u00f3n p\u00fablica, te dar\u00e1 proyecci\u00f3n exterior, pero te resta credibilidad en la plantilla de VW Navarra, siendo una pol\u00edtica empresarial err\u00f3nea y deleznable.<\/p>\n\n\n\n<p>Se deber\u00eda legislar para imposibilitar el acceso a todo tipo de subvenciones p\u00fablicas a aquellas empresas que tienen por costumbre incumplir la legislaci\u00f3n en materia laboral, solo as\u00ed se acabar\u00eda con esta lacra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ra\u00fal Portillo Alzueta, Secretario General de la Secci\u00f3n Sindical de LAB en VW Navarra, y miembro del Comit\u00e9 de Empresa de VW Navarra. La Direcci\u00f3n de VW Navarra habitualmente emplea a los medios de comunicaci\u00f3n como herramienta de presi\u00f3n medi\u00e1tica, propaganda y desinformaci\u00f3n, mentir no es informar. Recientemente VW publicaba a los 4 vientos: \u201cEn [&hellip;]<\/p>\n","protected":false},"author":1191,"featured_media":80874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18,2868],"tags":[2979,1158,5444,1650],"class_list":{"0":"post-88215","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"category-industria-es","9":"tag-industria-2","10":"tag-iritzia","11":"tag-raul-portillo-alzueta","12":"tag-volkswagen"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=88215"}],"version-history":[{"count":2,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88215\/revisions"}],"predecessor-version":[{"id":89230,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/88215\/revisions\/89230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/80874"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=88215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=88215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=88215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}