{"id":78237,"date":"2025-02-14T11:18:10","date_gmt":"2025-02-14T11:18:10","guid":{"rendered":"https:\/\/www.lab.eus\/?p=78237"},"modified":"2025-02-14T11:18:13","modified_gmt":"2025-02-14T11:18:13","slug":"lab-se-moviliza-en-siete-hospitales-para-reclamar-la-actualizacion-de-las-listas-de-contratacion-de-osakidetza","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/lab-se-moviliza-en-siete-hospitales-para-reclamar-la-actualizacion-de-las-listas-de-contratacion-de-osakidetza\/","title":{"rendered":"LAB se moviliza en siete hospitales para reclamar la actualizaci\u00f3n de las listas de contrataci\u00f3n de Osakidetza"},"content":{"rendered":"\n<p>El sindicato se ha concentrado ante los hospitales de Galdakao, Urduliz, Cruces, Basurto, Donostia, Txagorritxu y Santiago para denunciar que la direcci\u00f3n de Osakidetza lleva m\u00e1s de un a\u00f1o sin actualizar las listas de contrataci\u00f3n temporal incumpliendo el actual protocolo de contrataci\u00f3n.<\/p>\n\n\n\n<p>LAB ha se\u00f1alado que no se hacen las incorporaciones de las nuevas personas inscritas, no se han actualizado las listas con las notas de la OPE 2018-2019 y cuando las y los trabajadores solicitan cambiar alguna de las OSIs elegidas el cambio no sale reflejado.<\/p>\n\n\n\n<p>Todo esto es una vulneraci\u00f3n del derecho al trabajo, especialmente del personal eventual y de la ciudadan\u00eda en general que aspira acceder a un empleo en el Ente P\u00fablico. La direcci\u00f3n de Osakidetza est\u00e1 incumpliendo el acuerdo de contrataci\u00f3n. Este es un acuerdo reciente y de los pocos alcanzados en la \u00faltima d\u00e9cada. La lectura que hacemos desde el sindicato LAB es que los acuerdos en Osakidetza no son garant\u00eda de nada.<\/p>\n\n\n\n<p>La aplicaci\u00f3n habilitada para controlar el estado de las contrataciones y que es una herramienta para arrojar un m\u00ednimo de transparencia a la gesti\u00f3n de las listas ha tenido largos periodos de mal funcionamiento. Esto ha situado a todas las personas integrantes de las listas de contrataci\u00f3n en una situaci\u00f3n de indefensi\u00f3n absoluta.<\/p>\n\n\n\n<p>Para LAB la responsabilidad est\u00e1 en el modelo de colaboraci\u00f3n p\u00fablico-privado que el PNV insiste en vender como soluci\u00f3n para todos los males.<\/p>\n\n\n\n<p>Por todos y todas es conocido que las aplicaciones inform\u00e1ticas que Osakidetza utilizar para estos procesos son dise\u00f1adas, en su gran mayor\u00eda, por empresas externas. Estas empresas se embolsan grandes cantidades de dinero p\u00fablico y, en demasiadas ocasiones, no superan ni el m\u00ednimo de eficacia exigible.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"552\" data-id=\"78235\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-1024x552.jpg\" alt=\"\" class=\"wp-image-78235\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-1024x552.jpg 1024w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-300x162.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-768x414.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-780x420.jpg 780w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-150x81.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-696x375.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz-1068x575.jpg 1068w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Urduliz.jpg 1255w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"78233\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-1024x768.jpg\" alt=\"\" class=\"wp-image-78233\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-1024x768.jpg 1024w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-300x225.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-768x576.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-560x420.jpg 560w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-80x60.jpg 80w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-150x113.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-696x522.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu-1068x801.jpg 1068w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Txagorritxu.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"989\" height=\"412\" data-id=\"78229\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Donostia.jpg\" alt=\"\" class=\"wp-image-78229\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Donostia.jpg 989w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Donostia-300x125.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Donostia-768x320.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Donostia-150x62.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/02\/Osakidetza_Donostia-696x290.jpg 696w\" sizes=\"auto, (max-width: 989px) 100vw, 989px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El sindicato se ha concentrado ante los hospitales de Galdakao, Urduliz, Cruces, Basurto, Donostia, Txagorritxu y Santiago para denunciar que la direcci\u00f3n de Osakidetza lleva m\u00e1s de un a\u00f1o sin actualizar las listas de contrataci\u00f3n temporal incumpliendo el actual protocolo de contrataci\u00f3n.<\/p>\n","protected":false},"author":1191,"featured_media":78231,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18,2867,3097,6],"tags":[3033,3178,5183,3195,3100,3171],"class_list":{"0":"post-78237","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"category-federaciones","9":"category-sanidad","10":"category-es-servicios-publicos","11":"tag-accion-sindical-es","12":"tag-destacado-1","13":"tag-listas-de-contratacion","14":"tag-osakidetza-es","15":"tag-sanidad-es","16":"tag-servicios-publicos-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/78237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=78237"}],"version-history":[{"count":1,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/78237\/revisions"}],"predecessor-version":[{"id":78238,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/78237\/revisions\/78238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/78231"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=78237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=78237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=78237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}