{"id":47899,"date":"2022-05-24T08:21:46","date_gmt":"2022-05-24T08:21:46","guid":{"rendered":"https:\/\/www.lab.eus\/?p=47899"},"modified":"2022-05-24T08:30:41","modified_gmt":"2022-05-24T08:30:41","slug":"hemos-denunciado-la-muerte-laboral-del-repartidor-fallecido-en-zamudio","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/hemos-denunciado-la-muerte-laboral-del-repartidor-fallecido-en-zamudio\/","title":{"rendered":"Hemos denunciado la muerte laboral del repartidor fallecido en Zamudio"},"content":{"rendered":"\n<p>Nos hemos concentrado para recordar al <a href=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/05\/20-LAB_hildako-langileak_ES-1.pdf\">repartidor fallecido la semana pasada en Zamudio<\/a>. Hemos realizado la movilizaci\u00f3n frente a la sede de Tamar Restauraci\u00f3n y Catering, a llamamiento del comit\u00e9 de empresa. En concreto, el fallecido era trabajador de la empresa Vancuver Servicios Dirrectos, subcontratada por la citada empresa.<\/p>\n\n\n\n<p>La precariedad se ha llevado este a\u00f1o a <a href=\"https:\/\/www.lab.eus\/2022an-lan-istripuan-hildako-langileak\/\">30 trabajadoras y trabajadores<\/a> en Euskal Herria. La situaci\u00f3n es insostenible. Las instituciones deben situar el tema en la agenda pol\u00edtica sin esperar m\u00e1s.<\/p>\n\n\n\n<p><strong>Comunicado del comit\u00e9 de empresa de Tamar con motivo de la citada muerte laboral:<\/strong><\/p>\n\n\n\n<p>El comit\u00e9 de empresa de TAMAR LAS ARENAS quiere denunciar el accidente laboral mortal del pasado jueves 19 de mayo en Zamudio, donde un trabajador de una empresa subcontratada por la empresa Tamar falleci\u00f3 cuando realizaba tareas de reparto con la furgoneta.<\/p>\n\n\n\n<p>La siniestralidad laboral no para de aumentar y ya se ha llevado por delante la vida de 30 trabajadoras y trabajadores en Hego Euskal Herria en lo que va de a\u00f1o, dato totalmente inaceptable, insostenible y vergonzoso.<\/p>\n\n\n\n<p>La precariedad laboral y la falta de inversi\u00f3n en prevenci\u00f3n deja detr\u00e1s de si sufrimiento y muerte. A\u00fan desconociendo todav\u00eda las causas del fallecimiento, queremos apuntar que el trabajo de reparto entra\u00f1a muchos riesgos especialmente en cuanto a estr\u00e9s y ritmos de trabajo que incrementan la probabilidad de sufrir un accidente. Otra causa estructural son los altos niveles de subcontrataci\u00f3n que existe, donde las condiciones de las y los trabajadores son especialmente precarias.<\/p>\n\n\n\n<p>Es prioritario cambiar de direcci\u00f3n en materia de seguridad y salud laboral para poner freno a la precariedad laboral, que es el origen de tanto accidente laboral y enfermedad profesional. Si no se antepone la prevenci\u00f3n a la producci\u00f3n, m\u00e1s personas seguir\u00e1n enfermando y muriendo.<\/p>\n\n\n\n<p>Desde aqu\u00ed, queremos expresar a la familia y compa\u00f1eros de Kepa nuestros apoyo y solidaridad, y al mismo tiempo exigir a las administraciones que dejen de mirar para otro lado y pongan los medios necesarios para que termine esta masacre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos hemos concentrado frente a la sede de Tamar Restauraci\u00f3n y Catering, a llamamiento del comit\u00e9 de empresa. El fallecido era trabajador de la empresa Vancuver Servicios Dirrectos, subcontratada por la citada empresa.<\/p>\n","protected":false},"author":1189,"featured_media":47897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18,130,15],"tags":[3033,3178,3083],"class_list":{"0":"post-47899","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"category-es-la-precariedad-mata-es-salud-laboral","9":"category-es-salud-laboral","10":"tag-accion-sindical-es","11":"tag-destacado-1","12":"tag-salud-laboral-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/47899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=47899"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/47899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/47897"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=47899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=47899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=47899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}