{"id":45223,"date":"2022-03-23T08:25:34","date_gmt":"2022-03-23T08:25:34","guid":{"rendered":"https:\/\/www.lab.eus\/?p=45223"},"modified":"2022-03-23T08:25:51","modified_gmt":"2022-03-23T08:25:51","slug":"abordaremos-en-el-palacio-euskalduna-el-papel-de-los-sindicatos-soberanistas-en-el-proceso-de-transformacion-del-contexto-europeo","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/abordaremos-en-el-palacio-euskalduna-el-papel-de-los-sindicatos-soberanistas-en-el-proceso-de-transformacion-del-contexto-europeo\/","title":{"rendered":"Abordaremos en el Palacio Euskalduna el papel de los sindicatos soberanistas en el proceso de transformaci\u00f3n del contexto europeo"},"content":{"rendered":"\n<p>Procesos de transformaci\u00f3n en Europa. Este es el tema que abordaremos el jueves, en el Palacio Euskalduna de Bilbo, con motivo del encuentro de sindicatos soberanistas organizado por el sindicato LAB. En concreto, por la ma\u00f1ana y por la tarde, estar\u00e1n presentes representantes de sindicatos procedentes de Catalunya, Galiza, Arag\u00f3n, Asturies, Pa\u00eds Valenci\u00e0, Canarias, C\u00f3rcega, Cerde\u00f1a, Aosta, Canarias, Irlanda y Escocia, bajo el amparo de LAB. Tambi\u00e9n estar\u00e1n, como invitados, otros sindicatos vascos.<\/p>\n\n\n\n<p>Con este encuentro de sindicatos y sindicalistas del contexto europeo queremos destacar la importancia de crear alianzas, ya que los sindicatos soberanistas tenemos herramientas para transformar la Europa de las \u00e9lites econ\u00f3micas y de los estados.<\/p>\n\n\n\n<p>As\u00ed las cosas, en la fase post-pandemia y en un contexto golpeado por la invasi\u00f3n ucraniana, reflexionaremos sobre los retos que tenemos los sindicatos soberanistas en defensa del pueblo trabajador.<\/p>\n\n\n\n<p>La jornada comenzar\u00e1 a las 9:00, con la intervenci\u00f3n de la secretaria general de LAB, Garbi\u00f1e Aranburu. A continuaci\u00f3n, cada sindicato hablar\u00e1 sobre la situaci\u00f3n de su pa\u00eds. Concluido esto, todos abordaremos el contexto internacional, con el sindicalismo soberanista como alternativa de transformaci\u00f3n. El turno de conclusiones llegar\u00e1 por la tarde, y a continuaci\u00f3n, sobre las 17:30, se llevar\u00e1 a cabo el acto de clausura. Presentaremos as\u00ed los consensos alcanzados en los encuentros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves, durante todo el d\u00eda, representantes de sindicatos llegados de Catalunya, Galiza, Arag\u00f3n, Asturies, Pa\u00eds Valenci\u00e0, Canarias, C\u00f3rcega, Cerde\u00f1a, Aosta, Canarias, Irlanda y Escocia participar\u00e1n en los encuentros organizados por LAB, en base a la importancia de crear alianzas.<\/p>\n","protected":false},"author":1189,"featured_media":45229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3402,4,11],"tags":[3178,3173],"class_list":{"0":"post-45223","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-accion-politica","8":"category-es-internacional","9":"category-es-sindicato-lab","10":"tag-destacado-1","11":"tag-internacional-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/45223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=45223"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/45223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/45229"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=45223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=45223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=45223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}