{"id":44945,"date":"2022-03-16T18:17:00","date_gmt":"2022-03-16T18:17:00","guid":{"rendered":"https:\/\/www.lab.eus\/?p=44945"},"modified":"2022-03-17T08:19:46","modified_gmt":"2022-03-17T08:19:46","slug":"hemos-denunciado-el-desahucio-de-inaki-y-rosa-mari-y-expresamos-nuestro-apoyo-a-todas-las-vecinas-afectadas-por-el-fondo-buitre-azora-en-donostia","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/hemos-denunciado-el-desahucio-de-inaki-y-rosa-mari-y-expresamos-nuestro-apoyo-a-todas-las-vecinas-afectadas-por-el-fondo-buitre-azora-en-donostia\/","title":{"rendered":"Hemos denunciado el desahucio de I\u00f1aki y Rosa Mari y expresamos nuestro apoyo a todas las vecinas afectadas por el fondo buitre Azora en Donostia"},"content":{"rendered":"\n<p>Queremos denunciar que hoy se ha llevado a cabo el desahucio de dos vecinas que residen en el edificio de Ategorrieta 43 de Donostia y que, una vez m\u00e1s, la operaci\u00f3n se ha llevado a cabo con total protecci\u00f3n policial y violencia contra las personas ah\u00ed reunidas.<\/p>\n\n\n\n<p>Las vecinas han denunciado desde el principio la ofensiva del fondo buitre Azora y su situaci\u00f3n, dando a conocer la cara m\u00e1s cruda de la problem\u00e1tica de la vivienda que sufrimos en Donostia. Nos sumamos a la lucha que las vecinas han emprendido por el derecho a vivir y envejecer en el barrio y queremos mostrar toda nuestra solidaridad con las vecinas que se han quedado sin casa, I\u00f1aki y Mar\u00eda Rosa. Adem\u00e1s, exigimos al ayuntamiento una alternativa de vivienda cuanto antes.<\/p>\n\n\n\n<p>Desde que el fondo buitre Azora aterrizara en Donostia comprando pisos de la Inmboliaria Vascongada, decenas de vecinas han sufrido las consecuencias de la especulaci\u00f3n de la vivienda, entre ellas subidas del alquiler del 33% y pr\u00f3rrogas de contrato de un mes, con amenazas de desahucio entre medio. Por otro lado, hace 6 a\u00f1os el gobierno municipal declar\u00f3 Donostia ciudad libre de desahucios y desde entonces, en el marco de una mediaci\u00f3n para gestionar las situaciones de desahucio, el PNV, lejos de abordar el problema de ra\u00edz, ha intentado conseguir no ofrecer im\u00e1genes inapropiadas de la ciudad que este tipo de hechos antisociales implican.<\/p>\n\n\n\n<p>Hoy, ante los intereses y poder de los fondos buitres se ha puesto de manifiesto la hipocres\u00eda de Eneko Goia. Por lo tanto, exigimos que los gobiernos garanticen la necesidad de llevar a la pr\u00e1ctica el derecho subjetivo a la vivienda.<\/p>\n\n\n\n<p>La mercantilizaci\u00f3n y la especulaci\u00f3n con la vivienda es uno de los principales ejes de precarizaci\u00f3n de las condiciones de vida de la clase trabajadora vasca. Por tanto, <a href=\"https:\/\/www.lab.eus\/es\/abiatu-la-nueva-comunidad-de-accion-social-ha-reclamado-una-vivienda-digna-y-accesible-para-todas-y-todos-los-trabajadores\/\">como hemos reivindicado con la campa\u00f1a y l\u00ednea de trabajo de vivienda que hemos lanzado desde ABIATU<\/a>, exigimos cuanto antes que los gobiernos garanticen la obligaci\u00f3n de hacer efectivo el derecho subjetivo a la vivienda, regulando los precios de la vivienda y priorizando el alquiler social, ampliando el parque p\u00fablico, expropiando fondos buitres y grandes propiedades y paralizando TODOS los desahucios.<\/p>\n\n\n\n<p>La vivienda es un derecho, no un negocio. Pedimos paralizar todos los deshaucios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vivienda es un derecho, no un negocio. Pedimos paralizar todos los deshaucios.<\/p>\n","protected":false},"author":1189,"featured_media":44943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2994,377,2898,3283],"tags":[3182,3178],"class_list":{"0":"post-44945","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-accion-social","8":"category-es-deshaucios","9":"category-precariedad-y-pobreza","10":"category-sin-categorizar","11":"tag-accion-social-es","12":"tag-destacado-1"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/44945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=44945"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/44945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/44943"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=44945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=44945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=44945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}