{"id":44916,"date":"2022-03-16T13:41:39","date_gmt":"2022-03-16T13:41:39","guid":{"rendered":"https:\/\/www.lab.eus\/?p=44916"},"modified":"2022-03-16T13:44:44","modified_gmt":"2022-03-16T13:44:44","slug":"hemos-presentado-el-proyecto-de-ley-de-codigo-laboral-y-seguridad-social-de-euskal-herria-en-la-comision-de-trabajo-y-empleo-del-parlamento-de-gasteiz-con-el-reparto-del-empleo-de-los-cuidados-y-de","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/hemos-presentado-el-proyecto-de-ley-de-codigo-laboral-y-seguridad-social-de-euskal-herria-en-la-comision-de-trabajo-y-empleo-del-parlamento-de-gasteiz-con-el-reparto-del-empleo-de-los-cuidados-y-de\/","title":{"rendered":"Hemos presentado el proyecto de ley de C\u00f3digo Laboral y Seguridad Social de Euskal Herria en el Parlamento de Gasteiz, con el reparto del empleo, de los cuidados y de la riqueza como ejes"},"content":{"rendered":"\n<p>Xabier Ugartemendia, secretario de Acci\u00f3n Sindical y Negociaci\u00f3n Colectiva de LAB, y Oihana Lopetegi, responsable de estudios y an\u00e1lisis, han comparecido en la Comisi\u00f3n de Trabajo y Empleo del Parlamento Gasteiz para explicar los pormenores del <a href=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2021\/10\/PROPUESTA.pdf\">proyecto de ley de C\u00f3digo Laboral y Seguridad Social de Euskal Herria<\/a> elaborado por el sindicato.<\/p>\n\n\n\n<p>Concretamente, la citada propuesta, que <a href=\"https:\/\/www.lab.eus\/es\/hemos-interpelado-al-parlamento-de-gasteiz-para-que-construya-una-hoja-de-ruta-con-el-objetivo-de-avanzar-en-la-soberania-y-mejorar-las-condiciones-de-trabajo-y-de-vida-con-las-actuales-competencias\/\">fue registrada en el Parlamento de Gasteiz el pasado mes de octubre<\/a>, se basa en el triple reparto reivindicado por LAB, es decir, en el reparto del empleo, de los cuidados y de la riqueza. As\u00ed, en la proposici\u00f3n de ley de C\u00f3digo Laboral y Seguridad Social contemplamos medidas para que ese reparto se realice de forma equilibrada.<\/p>\n\n\n\n<p>Los miembros de LAB han explicado que esta propuesta, elaborada para el conjunto de Euskal Herria, no es cerrada, ya que la enmarcamos en un debate a abordar para definir qu\u00e9 tipo de relaciones laborales, qu\u00e9 tipo de derechos y obligaciones y qu\u00e9 tipo de sistema de protecci\u00f3n queremos.<\/p>\n\n\n\n<p>En palabras de Xabier Ugartemendia, \u00absituamos estas propuestas en la construcci\u00f3n de un nuevo modelo, pero eso no significa que desde hoy mismo no podamos empezar a trabajar en la direcci\u00f3n que recogemos en nuestras propuestas\u00bb.<\/p>\n\n\n\n<p><strong>Reconocimiento de todos los trabajos<\/strong><\/p>\n\n\n\n<p>En el C\u00f3digo Laboral planteamos la necesidad de reconocer y redistribuir todos los trabajos, incluidos los de cuidados. Asimismo, recogemos propuestas para acabar con la divisi\u00f3n sexual del trabajo y medidas para dignificar los salarios y el empleo. Son propuestas para repartir empleo, cuidados y riqueza, tal y como hemos citado anteriormente.<\/p>\n\n\n\n<p>En cuanto a la Ley de Seguridad Social propia incluimos medidas para garantizar pensiones p\u00fablicas y una protecci\u00f3n social digna.<\/p>\n\n\n\n<p>Se trata, en definitiva, de la aportaci\u00f3n de LAB a la construcci\u00f3n del marco vasco de relaciones laborales y protecci\u00f3n social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos se\u00f1alado que la propuesta, elaborada para el conjunto de Euskal Herria, no es cerrada, ya que la enmarcamos en un debate a abordar para definir qu\u00e9 tipo de relaciones laborales, qu\u00e9 tipo de derechos y obligaciones y qu\u00e9 tipo de sistema de protecci\u00f3n queremos.<\/p>\n","protected":false},"author":1189,"featured_media":44936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3402,18,2994,3283,11],"tags":[3033,3182,3180,3260],"class_list":{"0":"post-44916","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-accion-politica","8":"category-es-accion-sindical","9":"category-accion-social","10":"category-sin-categorizar","11":"category-es-sindicato-lab","12":"tag-accion-sindical-es","13":"tag-accion-social-es","14":"tag-destacado-3","15":"tag-sindicato-lab-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/44916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=44916"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/44916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/44936"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=44916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=44916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=44916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}