{"id":36591,"date":"2021-06-28T10:22:33","date_gmt":"2021-06-28T10:22:33","guid":{"rendered":"https:\/\/www.lab.eus\/?p=36591"},"modified":"2021-06-28T10:22:47","modified_gmt":"2021-06-28T10:22:47","slug":"las-trabajadoras-de-limpieza-subcontratadas-de-osakidetza-se-movilizaran-en-defensa-de-unas-condiciones-laborales-dignas","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/las-trabajadoras-de-limpieza-subcontratadas-de-osakidetza-se-movilizaran-en-defensa-de-unas-condiciones-laborales-dignas\/","title":{"rendered":"Las trabajadoras de limpieza subcontratadas de Osakidetza se movilizar\u00e1n en defensa de unas condiciones laborales dignas"},"content":{"rendered":"\n<p>El personal de limpieza subcontratado de Osakidetza llevamos moviliz\u00e1ndonos desde el pasado mes de octubre. Inicialmente lo hizimos junto a la plantilla de Osakidetza, en demanda de un servicio p\u00fablico de calidad y en denuncia de los recortes en el servicio. Desde el mes de mayo contin\u00faamos, ahora en solitario, en demanda de un convenio digno para el sector.<\/p>\n\n\n\n<p>Pese a haber recibido aplausos y agradecimientos por el papel jugado y la valent\u00eda mostrada en su esfuerzo por frenar la pandemia, sus revindicaciones han sido ninguneadas. La situaci\u00f3n de las limpiadoras en los centros de salud ya era dif\u00edcil antes de la pandemia, el trabajo es extenuante; las bajas no se cubren, el personal es insuficiente. La pandemia no ha hecho m\u00e1s que recrudecer esta realidad. Estamos en m\u00ednimos. Sin embargo, las empresas se muestran impasibles, reuni\u00f3n tras reuni\u00f3n nunca nada que ofrecer, en una clara estrategia por mantener bloqueado el convenio. Esta actitud tan censurable por parte de las empresas, ha sido tambi\u00e9n mantenida por el propio departamento p\u00fablico de salud, que ha ignorado todas y cada una de las solicitudes de reuni\u00f3n que se le han enviado.<\/p>\n\n\n\n<p>Tres a\u00f1os de negociaci\u00f3n y la situaci\u00f3n continua enroscada. Demandamos una carrera profesional que ten\u00eda que haberse reconocido en 2012, posibilidad de ampliar nuestras jornadas parciales a medida que se vayan produciendo vacantes, revisi\u00f3n de la sobrecarga de trabajo y seguridad y salud laboral en nuestros puestos.<\/p>\n\n\n\n<p>El pasado 27 de mayo convocamos una jornada de huelga. Una huelga a la que las administraciones respondieron con la imposici\u00f3n de un 100% de servicios m\u00ednimos.<\/p>\n\n\n\n<p>Sin embargo y pese a todos los obstaculos, hemos decidido seguir moviliz\u00e1ndonos y es por ello, que el pr\u00f3ximo martes, 29 de junio, vestiremos nuestros uniformes de desinfecci\u00f3n una vez m\u00e1s, en una movilizaci\u00f3n que se llevar\u00e1 a cabo a las 11:30 frente al Hospital de Cruces.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes vestir\u00e1n sus uniformes de desinfecci\u00f3n una vez m\u00e1s, en una movilizaci\u00f3n que se llevar\u00e1 a cabo a las 11:30 frente al Hospital de Cruces.<\/p>\n","protected":false},"author":1189,"featured_media":36589,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[18,2944,8],"tags":[3033,3178,3172],"class_list":{"0":"post-36591","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-accion-sindical","8":"category-limpieza","9":"category-es-servicios-privados","10":"tag-accion-sindical-es","11":"tag-destacado-1","12":"tag-servicios-privados-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/36591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=36591"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/36591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/36589"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=36591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=36591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=36591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}