{"id":299,"date":"2011-12-07T07:17:31","date_gmt":"2011-12-07T07:17:31","guid":{"rendered":"https:\/\/www.lab.eus\/euskal-preso-eta-iheslari-politikoak-etxera\/"},"modified":"2020-07-15T10:17:13","modified_gmt":"2020-07-15T10:17:13","slug":"euskal-preso-eta-iheslari-politikoak-etxera","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/euskal-preso-eta-iheslari-politikoak-etxera\/","title":{"rendered":"Euskal preso eta iheslari politikoak etxera!"},"content":{"rendered":"<div align=\"justify\" style=\" color: rgb(0, 0, 0); text-decoration: none; background-image: none; background-attachment: initial; background-origin: initial; background-clip: initial; background-color: initial; font-size: 12px; background-repeat: repeat repeat; \">Euskal preso politikoen kontra erabiltzen den espetxe politika tristeki aski ezaguna da gure herrian: 20 urte baino gehiago irauten duen sakabanaketa, isolamendua, etengabeko xantaia, de facto aplikatzen zaien bizi osorako zigorra&#8230; Salbuespeneko kartzela politika hau, gainera, azken urteotan larriki gogortuz joan da, euskal preso politikoen kontra espresuki sortutako hainbat neurri eta dotrinen bitartez.<\/p>\n<p> Espetxe politika hau, oinarrizko eskubideak ere ukatzen eta zapaltzen dituena, errepresioan eta mendekuan oinarritzeaz gain,&nbsp;<b>Estatuek erabili izan dute gatazka politikorako baldintzatze-tresna gisa: politika berezia izaera politikoa daukan kolektibo baten kontra. Politika kriminal honek lehen ez zeukan lekurik, baina gure herrian zabaldu den garai berri honetan are gutxiago.&nbsp;<\/b>Preso eta iheslari politikoen existentzia hutsa gatazka politikoaren ondorioa da eta Estatuek espetxe politika honi eustea ikaragarrizko oztopoa da konponbide prozesurako.<\/p>\n<p> Estatuei dagokie urratsak egitea. Orain. Baina urrats horiek egitera behartzea denon erantzukizuna da. Estatuak ez dira berez mugituko horrela aldarrikatzen dion gehiengo batek horretara behartzen ez baditu.&nbsp;<b>Espetxe politika kritikatzea, bidezkoa ez dela esatea ez da nahikoa. Esatetik egitera pasatu beharra dago egoera hau benetan gainditu nahi badugu. Borroka honetan konpromisoak hartu beharra daukagu, denok, norbanako zein eragileok.&nbsp;<\/b>Euskal preso eta iheslariak etxean nahi ditugu. Eta etxeratu egigo ditugu, nahiz eta bide oso bat egin behar, urratsez urrats joango gara bide hori ibiltzen. Amnistia da helburua: prozesu mailakatu batez aterabide politiko eta kolektiboa ematea.<\/p>\n<p> Urratsik premiazkoena espetxe politika behingoz aldatzea daukagu momentu honetan: salbuespenez ezarritako muturreko neurriak indargabeturik,<b>zigorra beteta daukaten presoak, hiru laurdenak beteta dauzkaten presoak, gaixorik dauden presoak aske egon behar dira, baldintzarik gabe.<\/b>&nbsp;Eta, honekin batera, sakabanaketa politikarekin amaituta,&nbsp;<b>euskal preso politiko guztiak Euskal Herrian behar dira egon.<\/b><\/p>\n<p> Euskal Herriko gehiengo zabalaren aldarrikapena da. Eta lantokiak ere aldarrikapen horren bozgorailu bihurtu behar ditugu, urteetako konpromisoa indartzeko eta beste batzuk aldarrikapen honekin konprometitzera erakartzeko. Lantokietan eta kalean, eskualdez eskualde, herriz herri, antolatzen diren ekimen ezbedinetan. Eta, jakina, urtarrilaren 7an. Bilboko kaleak bete behar ditugu espetxeak husteko.&nbsp;<b>Urtarrilaren 7an, ez ahaztu, ez da beste manifestazio bat, baizik eta euskal preso eta iheslari politikoak etxeratze bidean mugarria. Kolektibo oso baten borrokarekin bat egin eta Euskal Herriko kaleetatik aldarria zabaldu, berriro Euskal Herriko kaleetan izan ditzagun. Kolosala izan behar da. Kolosala izango da.<\/b><\/p>\n<p> <span style=\"font-size: medium; \"><b>euskal preso eta iheslari politikoak etxera!<\/b><br \/> <\/span><br \/> La pol&iacute;tica carcelaria desarrollada contra las presas y presos pol&iacute;ticos vascos es, por desgracia, suficientemente conocida en nuestro pa&iacute;s: la dispersi&oacute;n que se prolonga a lo largo de m&aacute;s de 20 a&ntilde;os, el aislamiento, el chantaje permanente, la cadena perpetua que se aplica de facto&#8230; Esta pol&iacute;tica carcelaria de excepci&oacute;n, adem&aacute;s, se ha ido endureciendo en los &uacute;ltimos a&ntilde;os de forma grave, a trav&eacute;s de numerosas medidas y doctrinas creadas expresamente contra las presas y presos pol&iacute;ticos vascos.<\/p>\n<p> Esta pol&iacute;tica penitenciaria que niega y vulnera los derechos b&aacute;sicos, adem&aacute;s de basarse en la represi&oacute;n y la venganza, es una herramienta que han utilizado los Estados para condicionar el conflicto pol&iacute;tico:<b>&nbsp;una pol&iacute;tica de excepci&oacute;n contra un colectivo de car&aacute;cter pol&iacute;tico. Esta pol&iacute;tica criminal no ten&iacute;a sentido anteriormente, pero en el nuevo tiempo que se ha abierto en nuestro pueblo, a&uacute;n menos.&nbsp;<\/b>La propia existencia del colectivo de personas presas y refugiadas pol&iacute;ticas es una consecuencia del conflicto pol&iacute;tico y la obstinaci&oacute;n de los Estados en mantener esta pol&iacute;tica carcelaria es un terrible obst&aacute;culo para el proceso de soluci&oacute;n.<\/p>\n<p> Corresponde a los estados dar pasos. Ahora. Pero obligarles a que den estos pasos es una responsabilidad de todos y todas. Los estados no se mover&aacute;n de forma espont&aacute;nea, si una mayor&iacute;a que lo reivindica no les obligue a ello.<b>&nbsp;Criticar la pol&iacute;tica penitenciaria, afirmar que no es justa, no es suficiente. Debemos pasar de las palabras a los hechos si de verdad queremos superar esta situaci&oacute;n. En esta lucha debemos adquirir compromisos, todos y todas, personas y agentes.<\/b>&nbsp;Queremos a los presos y presas, refugiados y refugiadas en casa. Y vamos a traerlos a casa. Aunque tengamos que recorrer todo un camino, lo haremos paso a paso, hasta lograr la amnist&iacute;a: una soluci&oacute;n pol&iacute;tica y colectiva a trav&eacute;s de un proceso gradual.<\/p>\n<p> En este momento, el paso m&aacute;s urgente es cambiar de una vez la pol&iacute;tica penitenciaria: hay que desactivar las medidas extremas de excepci&oacute;n,<b>&nbsp;las personas que ya ha cumplido la condena y siguen presas, las que han cumplido las tres cuartas partes o est&eacute;n enfermas deben ser liberadas, sin condiciones.&nbsp;<\/b>Junto con esto, hay que&nbsp;<b>terminar con la dispersi&oacute;n&nbsp;<\/b>para que las y los presos pol&iacute;ticos vascos est&eacute;n Euskal Herria.<\/p>\n<p> Se trata de una reivindicaci&oacute;n de la amplia mayor&iacute;a de Euskal Herria. Los centros de trabajo tambi&eacute;n deben convertirse en altavoz de esta reivindicaci&oacute;n, fortalecer el compromiso de a&ntilde;os y lograr que m&aacute;s gente se comprometa con ello. En la calle y en los centros de trabajo, en las distintas comarcas, pueblos y ciudades. Y por supuesto, el 7 de enero. Vamos a llenar las calles de Bilbo para, as&iacute;, vaciar las c&aacute;rceles.&nbsp;<b>La del 7 de enero, no lo olvid&eacute;is, no es una manifestaci&oacute;n m&aacute;s, sino un hito para situar a los presos y presas, refugiados y refugiadas pol&iacute;ticas de camino a casa. Unirnos a la lucha de todo un colectivo y extender la reivindicaci&oacute;n por las calles de Euskal Herria, para que vuelvan a esas calles de Euskal Herria. Tiene que ser colosal. Ser&aacute; colosal.<\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Euskal preso politikoen kontra erabiltzen den espetxe politika tristeki aski ezaguna da gure herrian: 20 urte baino gehiago irauten duen sakabanaketa, isolamendua, etengabeko xantaia, de facto aplikatzen zaien bizi osorako zigorra&#8230; Salbuespeneko kartzela politika hau, gainera, azken urteotan larriki gogortuz joan da, euskal preso politikoen kontra espresuki sortutako hainbat neurri eta dotrinen bitartez. Espetxe politika [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2],"tags":[1353],"class_list":{"0":"post-299","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-euskal-herria","7":"tag-euskal-herria"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/299\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}