{"id":28703,"date":"2020-11-04T16:13:33","date_gmt":"2020-11-04T16:13:33","guid":{"rendered":"https:\/\/www.lab.eus\/?p=28703"},"modified":"2020-11-04T16:13:35","modified_gmt":"2020-11-04T16:13:35","slug":"el-ayuntamiento-de-bilbo-reduce-el-servicio-de-limpieza-en-las-escuelas-publicas-en-plena-expansion-de-los-contagios","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/el-ayuntamiento-de-bilbo-reduce-el-servicio-de-limpieza-en-las-escuelas-publicas-en-plena-expansion-de-los-contagios\/","title":{"rendered":"El ayuntamiento de Bilbo reduce el servicio de limpieza en las escuelas p\u00fablicas en plena expansi\u00f3n de los contagios"},"content":{"rendered":"\n<p>El ayuntamiento de Bilbao ha decidido reducir el n\u00famero de horas anunciadas como refuerzo para la desinfecci\u00f3n y limpieza en los centros escolares.<\/p>\n\n\n\n<p>Al inicio del curso escolar, el ayuntamiento de Bilbao anunci\u00f3 una inversi\u00f3n de 200.000 euros adicionales destinados a reforzar el servicio de limpieza en las escuelas p\u00fablicas de la localidad. Dicha inversi\u00f3n se tradujo en la contrataci\u00f3n de una \u00fanica o dos personas, para centros que albergan a cientos de estudiantes y cuya duraci\u00f3n inicial se estim\u00f3 en 15 d\u00edas. Estos contratos se prorrogaron durante el primer mes, pero, ya en octubre, se produjeron los primeros recortes; jornadas que inicialmente eran de 7 horas\/diarias pasaron, de una semana a otra, a ser de 4 horas. Argumentaron haber sobredimensionado las necesidades reales de limpieza en los centros.<\/p>\n\n\n\n<p>Duranto todas estas semanas, no ha habido centro escolar en el que no se haya activado el protocolo covid por caso sospechoso o directamente por positivo confirmado.<\/p>\n\n\n\n<p>El viernes pasado, tuvimos conocimiento de un nuevo reajuste del servicio, una nueva reducci\u00f3n en el n\u00famero de horas contratadas. El refuerzo en la limpieza que se est\u00e1 llevando a cabo a d\u00eda de hoy en algunos centros roza la mitad de las horas que se anunciaron en un primer momento. Varias trabajadoras han visto rescindidos sus contratos.<\/p>\n\n\n\n<p>Desde el sindicato, LAB denunciamos esta actitud irresponsable del ayuntamiento, en un momento en el que el aumento del n\u00famero de contagios parece no frenar, decide unilateralmente reducir el refuerzo de limpieza en las escuelas.<\/p>\n\n\n\n<p>Exigimos al ayuntamiento que rectifique, que mantenga la inversi\u00f3n anunciada inicialmente en el servicio y que cese de colaborar en la precarizaci\u00f3n de las condiciones laborales de las limpiadoras, instando a la empresa subcontratada, UTE INTERIORES BILBAO II, a restaurar las jornadas de las trabajadoras, hacer indefinidos estos contratos y aumentando la contrataci\u00f3n para que la carga de trabajo asignada no sea inasumible, c\u00f3mo pretende que sea a d\u00eda de hoy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ayuntamiento de Bilbao ha decidido reducir el n\u00famero de horas anunciadas como refuerzo para la desinfecci\u00f3n y limpieza en los centros escolares.<\/p>\n","protected":false},"author":1189,"featured_media":28701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2944,8],"tags":[3172],"class_list":{"0":"post-28703","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-limpieza","8":"category-es-servicios-privados","9":"tag-servicios-privados-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/28703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=28703"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/28703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/28701"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=28703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=28703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=28703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}