{"id":28588,"date":"2020-10-30T08:55:44","date_gmt":"2020-10-30T08:55:44","guid":{"rendered":"https:\/\/www.lab.eus\/?p=28588"},"modified":"2020-10-30T08:55:46","modified_gmt":"2020-10-30T08:55:46","slug":"la-lucha-de-trenasa-no-ha-acabado-animamos-a-seguir-movilizandose-por-el-empleo","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/la-lucha-de-trenasa-no-ha-acabado-animamos-a-seguir-movilizandose-por-el-empleo\/","title":{"rendered":"La lucha de Trenasa no ha acabado; animamos a seguir moviliz\u00e1ndose por el empleo"},"content":{"rendered":"\n<p>Ante los hechos sucedidos en los \u00faltimos dos d\u00edas con respecto a la factor\u00eda Trenasa de Castej\u00f3n sobre la suspensi\u00f3n del ERE durante los pr\u00f3ximos tres meses, desde el sindicato LAB queremos recalcar que desde el primer momento hemos tenido claro que el ERE no se ajusta a la realidad de la empresa, puesto que cuenta con una viabilidad m\u00e1s que suficiente para seguir con su funcionamiento y con todos los proyectos y adjudicaciones que tiene entre manos. Consideramos que el planteamiento del ERE ha sido inoportuno e inadmisible y por ello desde el primer momento hemos mostrado y seguiremos mostrando nuestro rotundo rechazo a futuros planteamientos que tragan consigo un despido masivo de trabajadoras y trabajadores de Trenasa.<\/p>\n\n\n\n<p>Ya que se trata de una suspensi\u00f3n temporal, y no una decisi\u00f3n firme, emplazamos a los gobiernos y a la empresa a que reconsideren una decisi\u00f3n tan tr\u00e1gica como ser\u00eda el despido de 110 personas.<\/p>\n\n\n\n<p>Sabemos que la batalla no ha acabado y que esto contin\u00faa. Sin duda tenemos claro que lo que ha derivado hasta el momento en un par\u00e9ntesis para la empresa no ha sido otra cosa que la lucha obrera y la solidaridad de la clase trabajadora. Tenemos claro que sin esto no hubiesemos llegado al punto en que estamos, y por eso queremos remarcar que por encima de los despachos y reuniones, la ganadora de esta peque\u00f1a batalla -que no la guerra- ha sido la pelea en las calles, la presi\u00f3n social y la voluntad y deseo de la clase trabajadora por luchar en defensa de sus puestos de trabajo. Desde LAB, todo nuestro reconocimiento por ello.<\/p>\n\n\n\n<p>A pesar de que no tenemos delegados sindicales en Trenasa -pero s\u00ed una secci\u00f3n sindical&nbsp;&nbsp;activa y combativa-, desde el primer momento LAB ha querido aportar su granito de arena a una lucha que no es otra m\u00e1s que la de la clase trabajadora. Y all\u00ed donde haya una lucha de este tipo, all\u00ed estar\u00e1 LAB.<\/p>\n\n\n\n<p>Por \u00faltimo, queremos remarcar otra vez que esto no ha acabado, por lo que animamos a todas las personas a que sigan moviliz\u00e1ndose en favor del empleo de Trenasa. Del mismo modo queremos mandar nuestro \u00e1nimo a las personas que siguen encerradas en el Ayuntamiento de Castej\u00f3n. Desde LAB les enviamos todo nuestro cari\u00f1o, frente al empe\u00f1o que tienen algunos en bajar los brazos y volver al trabajo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante los hechos sucedidos en los \u00faltimos dos d\u00edas con respecto a la factor\u00eda Trenasa de Castej\u00f3n sobre la suspensi\u00f3n del ERE durante los pr\u00f3ximos tres meses, desde el sindicato LAB queremos recalcar que desde el primer momento hemos tenido claro que el ERE no se ajusta a la realidad de la empresa, puesto que cuenta con una viabilidad m\u00e1s que suficiente para seguir con su funcionamiento y con todos los proyectos y adjudicaciones que tiene entre manos. Consideramos que el planteamiento del ERE ha sido inoportuno e inadmisible y por ello desde el primer momento hemos mostrado y seguiremos mostrando nuestro rotundo rechazo a futuros planteamientos que tragan consigo un despido masivo de trabajadoras y trabajadores de Trenasa.<\/p>\n","protected":false},"author":1189,"featured_media":28586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2868,108],"tags":[3048,2996,3064],"class_list":{"0":"post-28588","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-industria-es","8":"category-es-metal","9":"tag-caf-es","10":"tag-industria-es","11":"tag-metal-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/28588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=28588"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/28588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/28586"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=28588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=28588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=28588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}