{"id":28494,"date":"2020-10-27T15:08:32","date_gmt":"2020-10-27T15:08:32","guid":{"rendered":"https:\/\/www.lab.eus\/?p=28494"},"modified":"2020-10-27T15:08:34","modified_gmt":"2020-10-27T15:08:34","slug":"denunciamos-el-boicot-a-la-huelga-de-las-y-los-trabajadores-de-la-estiba-del-puerto-de-bilbao","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/denunciamos-el-boicot-a-la-huelga-de-las-y-los-trabajadores-de-la-estiba-del-puerto-de-bilbao\/","title":{"rendered":"Denunciamos el boicot a la huelga de las y los trabajadores de la estiba del Puerto de Bilbao"},"content":{"rendered":"\n<p>El pasado domingo 25 a la ma\u00f1ana, se impidi\u00f3 el acceso a las y los trabajadores que iban a su puesto de trabajo dentro de las instalaciones del puerto.<\/p>\n\n\n\n<p>Tanto la Autoridad Portuaria y la Guardia Civil como la Ertzaintza realizaron un per\u00edmetro de control para el acceso de trabajadores que no son del puerto de Bilbao ni de la estiba, con el objetivo de sustituir a los trabajadores en huelga para sacar mercanc\u00edas del puerto, participando de forma activa en colaboraci\u00f3n con las empresas estibadoras usurpando un derecho fundamental como es el derecho a la huelga.<\/p>\n\n\n\n<p>Desde este sindicato consideramos que estos hechos son intolerables y hacemos directamente responsable de los mismos a Ricardo Barkala, nombrado por el PNV, a CEBEK y a las empresas estibadoras.<\/p>\n\n\n\n<p>De la misma manera, denunciamos los servicios m\u00ednimos abusvios que condenan a las y los trabajadores a garantizar un 100% en la mayor\u00eda de los casos, haciendo muy dif\u00edcil el normal desarrollo de una leg\u00edtima herramienta obrera, como es la huelga.<\/p>\n\n\n\n<p>Se\u00f1alamos como parte de la resoluci\u00f3n de este conflicto la inmediata readmisi\u00f3n de los 100 trabajadores despedidos y su incorporaci\u00f3n a la plantilla indefinida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se\u00f1alamos como parte de la resoluci\u00f3n de este conflicto la inmediata readmisi\u00f3n de los 100 trabajadores despedidos y su incorporaci\u00f3n a la plantilla indefinida.<\/p>\n","protected":false},"author":1189,"featured_media":28492,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2957,8],"tags":[3181,3172],"class_list":{"0":"post-28494","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-puertos","8":"category-es-servicios-privados","9":"tag-puertos","10":"tag-servicios-privados-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/28494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=28494"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/28494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/28492"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=28494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=28494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=28494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}