{"id":250,"date":"2011-11-23T11:24:03","date_gmt":"2011-11-23T11:24:03","guid":{"rendered":"https:\/\/www.lab.eus\/lab-exige-una-solucion-definitiva-y-duradera-para-los-trabajadores-y-trabajadoras-de-sunsundegui\/"},"modified":"2011-11-23T11:24:03","modified_gmt":"2011-11-23T11:24:03","slug":"lab-exige-una-solucion-definitiva-y-duradera-para-los-trabajadores-y-trabajadoras-de-sunsundegui","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/lab-exige-una-solucion-definitiva-y-duradera-para-los-trabajadores-y-trabajadoras-de-sunsundegui\/","title":{"rendered":"LAB exige una soluci\u00f3n definitiva y duradera para los trabajadores y trabajadoras de Sunsundegui"},"content":{"rendered":"<p>Desde el sindicato LAB, queremos mostrar nuestra preocupaci&oacute;n por la situaci&oacute;n que atraviesa la empresa Sunsundegui. El futuro de los puestos de trabajo y de la propia empresa sigue estando sin garant&iacute;as. <!--more-->  <br \/> En las &uacute;ltimas semanas han aparecido noticias en la prensa en torno a la posible entrada en Sunsundegui de un posible socio industrial, refiri&eacute;ndose a la carrocera gallega Castrosua. Pero la &uacute;ltima noticia en referencia a este asunto es que la carrocera gallega se ha echado para atr&aacute;s debido a que la noticia se filtr&oacute; a la prensa y las negociaciones se dan por rotas, esto est&aacute; dicho en boca de la consejera Lourdes Goikoetxea. Si esta situaci&oacute;n se ha dado por la filtraci&oacute;n a la prensa, exigimos responsabilidades y depurar si es necesario.<\/p>\n<p> Desde el sindicato LAB pedimos al Gobierno al Gobierno de Navarra que clarifique cuanto antes esta situaci&oacute;n y de explicaciones a los y las trabajadoras para saber que va ser del futuro de la planta, tambi&eacute;n exigimos m&aacute;s transparencia en la gesti&oacute;n que el Gobierno de Navarra realiza a trav&eacute;s de SODENA en Sunsundegui.<\/p>\n<p> En las dos reuniones mantenidas el comit&eacute; con la consejera Goikoetxea se dej&oacute; claro que el Gobierno hacia la opci&oacute;n de compra a trav&eacute;s de SODENA de forma transitoria y no muy prolongada en el tiempo, hasta encontrar una posible soluci&oacute;n a Sunsundegui, barajando algunas opciones, entre ellas la de buscar un socio industrial, cooperativa o la compra por parte de la actual direcci&oacute;n. Esta y no otra es la informaci&oacute;n que tiene el sindicato LAB.<\/p>\n<p> Despu&eacute;s de la firma del acuerdo el pasado 7 de Octubre por parte de los sindicatos ELA y UGT , en el que contiene entre otras cosas: reducci&oacute;n salarial, doble escala salarial, la destrucci&oacute;n de 40 puestos de trabajo de los cuales 21 de ellos han sido a dedo y de forma poco objetiva vi&eacute;ndose afectados la gente m&aacute;s comprometida, y nuestro sindicato el m&aacute;s afectado. Seg&uacute;n los firmantes de dicho acuerdo con su apoyo aseguraban el futuro de Sunsundegui. Nosotros nos preguntamos &iquest;donde est&aacute;n esas garant&iacute;as, de que tanto se hablan?<\/p>\n<p> Si alg&uacute;n sindicato maneja mas informaci&oacute;n de la que el resto podemos saber, nos gustar&iacute;a que esa informaci&oacute;n fuese compartida con el resto del comit&eacute;, porque todos representamos a las y los trabajadores por igual.<\/p>\n<p> Para finalizar pedimos al Gobierno de Navarra una soluci&oacute;n definitiva y duradera para los trabajadores y trabajadoras de Sunsundegui por el bien de su futuro y tambi&eacute;n de Altsasu y de toda Sakana, tan castigada por la crisis, apostando por el pleno empleo y de calidad.<br \/> &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el sindicato LAB, queremos mostrar nuestra preocupaci&oacute;n por la situaci&oacute;n que atraviesa la empresa Sunsundegui. El futuro de los puestos de trabajo y de la propia empresa sigue estando sin garant&iacute;as.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[111],"tags":[],"class_list":{"0":"post-250","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-errepideak"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=250"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/250\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}