{"id":22624,"date":"2020-08-25T06:26:00","date_gmt":"2020-08-25T06:26:00","guid":{"rendered":"https:\/\/www.lab.eus\/?p=22624"},"modified":"2020-08-27T06:29:18","modified_gmt":"2020-08-27T06:29:18","slug":"maltrato-y-abuso-sobre-las-y-los-profesionales-de-refuerzo-covid-en-osasunbidea","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/maltrato-y-abuso-sobre-las-y-los-profesionales-de-refuerzo-covid-en-osasunbidea\/","title":{"rendered":"Maltrato y abuso sobre las y los profesionales de refuerzo Covid en Osasunbidea"},"content":{"rendered":"\n<p><em>Contin\u00faa el ninguneo a la plantilla. Esta vez el problema son las horas de trabajo, y eso a pesar de que tanto LAB como la Comisi\u00f3n de Personal han presentado quejas en materia de contrataci\u00f3n.<br><br><\/em>La Direcci\u00f3n de Cuidados del Complejo Hospitalario de Navarra est\u00e1 aprovechando la falta de criterios claros y el desconocimiento de la legislaci\u00f3n vigente en materia de contrataci\u00f3n para vulnerar los derechos de las trabajadoras y trabajadores. Y lo hacen, adem\u00e1s, con el benepl\u00e1cito de la Direcci\u00f3n de Profesionales y la Gerencia del complejo, que est\u00e1n aprovechando esta situaci\u00f3n de vulneraci\u00f3n para eliminar derechos b\u00e1sicos de la plantilla por la falta de eficiencia en la gesti\u00f3n de contrataci\u00f3n.<\/p>\n\n\n\n<p>La Direcci\u00f3n de Cuidados est\u00e1 obligando a la plantilla a que recupere las horas en las que, durante el estado de alarma, estuvieron de ret\u00e9n para hacer frente a la posible demanda que pudiese producirse.<\/p>\n\n\n\n<p>Actualmente, aunque no est\u00e1n teniendo ning\u00fan problema para pagar productividades -debido a la falta de personal- a determinadas actividades y colectivos, pretenden que multitud de empleadas y empleados trabajen el mes de septiembre sin cobrarlo, bajo coacciones de determinadas jefaturas de unidad que est\u00e1n vulnerando la legislaci\u00f3n vigente (algunas trabajadoras ya han tenido que devolver las horas de ret\u00e9n, en periodo estival).<\/p>\n\n\n\n<p>Lo que est\u00e1 ocurriendo es que algunas unidades est\u00e1n ajustando calendarios, y la plantilla se ve obligada a devolver esas horas. Algunas empleadas han sufrido ya hasta tres ajustes de calendario en lo que va de a\u00f1o. Ha sido la nefasta organizaci\u00f3n del Servicio Navarro de Salud la responsable de que, mientras numerosos profesionales han tenido que permanecer en sus casas \u201cpor falta de carga de trabajo\u201d, en las plantas Covid o en Atenci\u00f3n Primaria entre otros no hayan podido contar con los recursos necesarios para responder con garant\u00edas a la incesante y vertiginosa actividad a la que han tenido que hacer frente. Esta mala organizaci\u00f3n no la pueden pagar los y las trabajadoras.<\/p>\n\n\n\n<p>Ante tal abuso, es importante recordar algunas cuestiones a nivel legal:<\/p>\n\n\n\n<p>&#8211; El 21 de junio de 2020 termin\u00f3 el estado de alarma regulado por el Decreto 463\/2020 de 14 de marzo y prorrogado hasta en seis ocasiones en las sesiones celebradas el 25 de marzo, 9 de abril, 22 de abril, 6 de mayo, 20 de mayo y 3 de junio de 2020.<\/p>\n\n\n\n<p>&#8211; El Real Decreto-ley 10\/2020, de 29 de marzo, por el que se regula un permiso retribuido recuperable, fue dictado para recuperar las horas no trabajadas desde el 30 de marzo hasta el 8 de abril en el caso de las empresas que siguieran trabajando en esa fecha, con el fin de que dicho personal se confinara. Este Real Decreto no es de aplicaci\u00f3n al personal que presta sus servicios en los denominados \u201cservicios esenciales\u201d. El Real Decreto 10\/2020 no es aplicable, por lo tanto, al personal de Osasunbidea al que se le est\u00e1 obligando a devolver las horas.<\/p>\n\n\n\n<p>&#8211; El Art\u00edculo 25.4 de la Ley 11\/1992, de 20 de octubre, establece que cada hora de trabajo que se realice sobre la duraci\u00f3n de la jornada establecida podr\u00e1 sustituirse por la compensaci\u00f3n econ\u00f3mica por tiempo de descanso a raz\u00f3n de:<br>&nbsp; &nbsp; &nbsp;-Por cada hora en d\u00eda laborable: una hora y cuarenta y cinco minutos.<br>&nbsp; &nbsp; &nbsp;-Por cada hora en domingo o festivo: dos horas.<\/p>\n\n\n\n<p>&#8211; Pago de complementos. Todo el personal que ha atendido pacientes Covid percibir\u00e1, por un lado, el complemento de turnicidad (sin necesidad de aplicar la condici\u00f3n de los tres meses) siempre y cuando haya tenido cambios de turno; y por otro, el 2% del complemento del riesgo. No hay diferencia entre fijos, eventuales con o sin vacante, o contratados por Covid; la Direcci\u00f3n del CHN ha hecho pago de estas horas con los listados que ha recibido por parte de las jefaturas de unidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contin\u00faa el ninguneo a la plantilla. Esta vez el problema son las horas de trabajo, y eso a pesar de que tanto LAB como la Comisi\u00f3n de Personal han presentado quejas en materia de contrataci\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":22623,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3097,86],"tags":[3196,1305,2986,3100,3171,3027],"class_list":{"0":"post-22624","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sanidad","8":"category-es-sanidad-publica-es-servicios-publicos","9":"tag-nafarroa-es-2","10":"tag-osasunbidea","11":"tag-sanidad-2","12":"tag-sanidad-es","13":"tag-servicios-publicos-es","14":"tag-servicios-publicos-3"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/22624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=22624"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/22624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/22623"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=22624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=22624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=22624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}