{"id":21271,"date":"2020-05-19T16:05:25","date_gmt":"2020-05-19T16:05:25","guid":{"rendered":"https:\/\/www.lab.eus\/es-necesario-acabar-con-la-legislacion-de-excepcion-y-poner-en-marcha-el-proceso-de-repatriacion-de-las-y-los-presos-vascos\/"},"modified":"2020-05-19T16:05:25","modified_gmt":"2020-05-19T16:05:25","slug":"es-necesario-acabar-con-la-legislacion-de-excepcion-y-poner-en-marcha-el-proceso-de-repatriacion-de-las-y-los-presos-vascos","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/es-necesario-acabar-con-la-legislacion-de-excepcion-y-poner-en-marcha-el-proceso-de-repatriacion-de-las-y-los-presos-vascos\/","title":{"rendered":"Es necesario acabar con la legislaci\u00f3n de excepci\u00f3n y poner en marcha el proceso de repatriaci\u00f3n de las y los presos vascos"},"content":{"rendered":"<p> <\/p>\n<div style=\"padding-right:15px;width:345px; float:left; border-right-style:solid; border-right-width:1px; border-right-color:#dddddd\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-21270\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_euskalHerria_euskalPresoak_20_05_19Presoak_40.jpg\" width=\"345\" height=\"237\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_euskalHerria_euskalPresoak_20_05_19Presoak_40.jpg 563w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_euskalHerria_euskalPresoak_20_05_19Presoak_40-300x206.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_euskalHerria_euskalPresoak_20_05_19Presoak_40-150x103.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_euskalHerria_euskalPresoak_20_05_19Presoak_40-218x150.jpg 218w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_euskalHerria_euskalPresoak_20_05_19Presoak_40-100x70.jpg 100w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><em><span style=\"font-size: 14px; \"><\/p>\n<p> Los agentes sociales, sindicales y pol&iacute;ticos de Euskal Herria hemos reclamado una y otra vez el fin de la pol&iacute;tica penitenciaria de excepci&oacute;n y la puesta en marcha del proceso de repatriaci&oacute;n de las y los presos vascos. Esta es la petici&oacute;n que ratificamos los sindicatos LAB, ELA, ESK, STEILAS, ETXALDE e HIRU, porque las y los presos vascos tienen derecho a recorrer el camino hacia la excarcelaci&oacute;n, porque este pueblo tiene derecho a recorrer el camino hacia la paz y la convivencia democr&aacute;tica.  <\/p>\n<p> <\/span><\/em>A pesar de algunos acercamientos y cambios de grado, los acontecimientos de las &uacute;ltimas semanas demuestran que la pol&iacute;tica penitenciaria de excepci&oacute;n sobre las y los presos vascos sigue vigente.  <\/p>\n<p> Hace 9 d&iacute;as que Patxi Ruiz inici&oacute; una huelga de hambre y sed tras las amenazas recibidas por parte de un funcionario de la c&aacute;rcel. La situaci&oacute;n es extrema y exigimos al Gobierno espa&ntilde;ol una soluci&oacute;n inmediata.  <\/p>\n<p> Por otro lado, el mes pasado, cuatro ciudadanos de Ipar Euskal Herria (Esnal, Haranburu y los hermanos Parot) cumplieron 30 a&ntilde;os desde su ingreso en prisi&oacute;n. La pol&iacute;tica penitenciaria no se puede basar en la venganza, por lo que exigimos a los gobiernos franc&eacute;s y espa&ntilde;ol que deroguen toda cadena perpetua.  <\/p>\n<p> Asimismo, la pandemia del COVID-19, que ha cambiado radicalmente nuestro d&iacute;a a d&iacute;a, ha tenido graves consecuencias en las c&aacute;rceles. La puesta en libertad de las y los presos enfermos y mayores en situaci&oacute;n de vulnerabilidad ha sido una medida adoptada por varios gobiernos, pero no ha ocurrido en el caso de las y los presos vascos. De nuevo, se les impone una medida de excepci&oacute;n, como es la de estar dispersadas y dispersados a cientos de kil&oacute;metros de Euskal Herria. En consecuencia, mientras el resto de presas y presos ha comenzado a recibir visitas de familiares y allegadas y allegados, a las y los presos vascos se les ha negado este derecho, ya que para acceder a la visita es necesario que sus allegadas y allegados pasen de un territorio a otro. Todas y todos los presos vascos deben ser acercados inmediatamente a Euskal Herria, sin excusas..<br \/> &nbsp;<\/div>\n<div style=\"width:180px; float:left; padding-left:15px;\">\n<div style=\"text-align: center; \"><a href=\"\/rssak\"><input src=\"\/materiala\/argazkiak\/feed.png\" alt=\"RSSak\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.facebook.com\/pages\/LAB-sindikatua\/292846207397345\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/facebook.png\" alt=\"LAB Facebooken\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/issuu.com\/lab_argitalpenak\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/issuu.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/es.scribd.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/scribd.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><br \/> <\/a><\/div>\n<div style=\"text-align: center; \"><a target=\"_blank\" href=\"http:\/\/twitter.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/twitter.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/labsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/youtube.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/lab-sindikatua\/\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/flickr.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a href=\"http:\/\/www.labsindikatua.org\/eu\/hasiera\/upload\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/igo.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><\/div>\n<p> &nbsp;<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los agentes sociales, sindicales y pol&iacute;ticos de Euskal Herria hemos reclamado una y otra vez el fin de la pol&iacute;tica penitenciaria de excepci&oacute;n y la puesta en marcha del proceso de repatriaci&oacute;n de las y los presos vascos. Esta es la petici&oacute;n que ratificamos los sindicatos LAB, ELA, ESK, STEILAS, ETXALDE e HIRU, porque las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3402,3301,2998],"tags":[],"class_list":{"0":"post-21271","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-accion-politica","8":"category-euskal-herria-es-2","9":"category-uncategorized-eu-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/21271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=21271"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/21271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/21270"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=21271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=21271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=21271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}