{"id":21254,"date":"2020-05-16T22:00:09","date_gmt":"2020-05-16T22:00:09","guid":{"rendered":"https:\/\/www.lab.eus\/rompamos-con-las-identidades-confinadas-acabemos-con-el-odio-en-las-casas-las-calles-y-lugares-de-trabajo\/"},"modified":"2020-05-16T22:00:09","modified_gmt":"2020-05-16T22:00:09","slug":"rompamos-con-las-identidades-confinadas-acabemos-con-el-odio-en-las-casas-las-calles-y-lugares-de-trabajo","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/rompamos-con-las-identidades-confinadas-acabemos-con-el-odio-en-las-casas-las-calles-y-lugares-de-trabajo\/","title":{"rendered":"\u00a1Rompamos con las identidades confinadas! \u00a1Acabemos con el odio en las casas, las calles y lugares de trabajo!"},"content":{"rendered":"<p> <\/p>\n<div style=\"padding-right:15px;width:345px; float:left; border-right-style:solid; border-right-width:1px; border-right-color:#dddddd\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-21253\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt.jpg\" width=\"345\" height=\"488\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt.jpg 1200w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-212x300.jpg 212w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-724x1024.jpg 724w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-768x1086.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-1086x1536.jpg 1086w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-150x212.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-300x424.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-696x984.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-1068x1510.jpg 1068w, https:\/\/www.lab.eus\/wp-content\/uploads\/2020\/05\/materiala_argazkiak_Arloak_desberdintasunenbehatokia_aniztasunSexuala_20_05_17Homofobia_Homofobia_opt-297x420.jpg 297w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><em><span style=\"font-size: 14px; \"><\/p>\n<p> 17 de mayo D&iacute;a contra la Homofobia, Lesbofobia, Transfobia y Bifobia. Desaparecido lo poco que ten&iacute;amos para vivir libremente la diversidad sexual, este estado de excepci&oacute;n nos ha confinado a&uacute;n m&aacute;s. Hogares hostiles, procesos para personas LGBTIQ+ paralizados, sin acceso a los servicios p&uacute;blicos&#8230; Este modelo de confinamiento que pone en el centro la familia nuclear y la heteronorma, supone nada m&aacute;s y nada menos que el aumento de casos de LGBTIQ+fobia en el hogar, en el trabajo y en la calle. <\/p>\n<p> <\/span><\/em>Hemos denunciado en m&aacute;s de una ocasi&oacute;n que esta crisis desencadenada por la covid-19 no es nueva, que las condiciones, posibilidades y servicios disponibles para vivir libremente antes de la pandemia eran muy limitados y escasos. <\/p>\n<p> Tenemos claro que el virus es el sistema cisheteropatriarcal que ataca, vulnera y reprime de forma reiterada nuestros cuerpos e identidades, por lo que decimos alto y claro que no, no queremos volver a la normalidad. Y tampoco queremos nuevas normalidades que busquen el lavado de cara de los estados opresores. Ni un capitalismo rosa, ni morado, ni verde, ni arco iris.<\/p>\n<p> Estamos muy preocupados porque, una vez m&aacute;s, las medidas adoptadas en el &aacute;mbito laboral golpean a los colectivos m&aacute;s vulnerables y los de los m&aacute;rgenes, como es el caso del colectivo LGTBIQ+. Vemos c&oacute;mo muchas personas han perdido su empleo, la situaci&oacute;n de extrema marginalidad de les trabajadores sexuales, el no atrevernos a vivir libremente en los lugares de trabajo debido a la mayor inestabilidad e inseguridad del mundo laboral y al hecho de que nos han metido el miedo hasta las entra&ntilde;as, y el aumento de la brecha salarial que sufrimos a las personas LGTBIQ+ y las mujeres.<\/p>\n<p> Las empresas tienen la obligaci&oacute;n de garantizar las condiciones para que no se produzca discriminaci&oacute;n alguna hacia nuestra diversidad sexual. Por lo tanto, exigimos no m&aacute;s despidos, la puesta en marcha de pol&iacute;ticas que garanticen el acceso de las personas trans al trabajo y que acaben con la brecha salarial. &iexcl;No vamos a permitir ataques encubiertos Lesbo-Homo-Trans-Bif&oacute;bicos del Capital bajo el pretexto de la crisis sanitaria!<\/p>\n<p> Adem&aacute;s, desde las instituciones p&uacute;blicas se est&aacute;n anunciando medidas que agravar&aacute;n esta situaci&oacute;n, ya que ahora que toca reforzar los gastos sociales de los presupuestos, se va a proceder a la reducci&oacute;n de los servicios p&uacute;blicos y, por tanto, de las pol&iacute;ticas de igualdad y de lucha contra la fobia LGBTIQ+. Es inaceptable. En LAB tenemos claro que para responder a esta crisis m&uacute;ltiple y evitar que los de siempre seamos quienes tengamos que pagar, hoy es imprescindible organizarnos y tomar medidas desde una perspectiva interseccional, poniendo en marcha medidas que garanticen la libertad sexual y de g&eacute;nero en los hogares, calles y lugares de trabajo.<\/p>\n<p> Asimismo, ante la difusi&oacute;n del miedo y la promoci&oacute;n del odio que fomenta el sistema capitalista heteropatriarcal, desde LAB seguiremos trabajando y luchando porque hoy sentimos con m&aacute;s fuerza lo esencial que son el cuidado, la organizaci&oacute;n sindical, la acci&oacute;n colectiva, los proyectos liberadores y las redes de solidaridad para poner la vida en el centro.<br \/> &nbsp;<\/div>\n<div style=\"width:180px; float:left; padding-left:15px;\">\n<div style=\"text-align: center; \"><a href=\"\/rssak\"><input src=\"\/materiala\/argazkiak\/feed.png\" alt=\"RSSak\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.facebook.com\/pages\/LAB-sindikatua\/292846207397345\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/facebook.png\" alt=\"LAB Facebooken\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/issuu.com\/lab_argitalpenak\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/issuu.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/es.scribd.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/scribd.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><br \/> <\/a><\/div>\n<div style=\"text-align: center; \"><a target=\"_blank\" href=\"http:\/\/twitter.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/twitter.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/labsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/youtube.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/lab-sindikatua\/\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/flickr.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a href=\"http:\/\/www.labsindikatua.org\/eu\/hasiera\/upload\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/igo.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><\/div>\n<p> &nbsp;<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>17 de mayo D&iacute;a contra la Homofobia, Lesbofobia, Transfobia y Bifobia. Desaparecido lo poco que ten&iacute;amos para vivir libremente la diversidad sexual, este estado de excepci&oacute;n nos ha confinado a&uacute;n m&aacute;s. Hogares hostiles, procesos para personas LGBTIQ+ paralizados, sin acceso a los servicios p&uacute;blicos&#8230; Este modelo de confinamiento que pone en el centro la familia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3281,2998],"tags":[3191],"class_list":{"0":"post-21254","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-secretaria-feminista","8":"category-uncategorized-eu-es","9":"tag-mujeres"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/21254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=21254"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/21254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/21253"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=21254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=21254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=21254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}