{"id":19075,"date":"2019-03-28T12:11:58","date_gmt":"2019-03-28T12:11:58","guid":{"rendered":"https:\/\/www.lab.eus\/la-plantilla-de-sunrise-medical-se-mantiene-en-huelga-ante-la-nula-voluntad-negociadora-de-la-direccion\/"},"modified":"2019-03-28T12:11:58","modified_gmt":"2019-03-28T12:11:58","slug":"la-plantilla-de-sunrise-medical-se-mantiene-en-huelga-ante-la-nula-voluntad-negociadora-de-la-direccion","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/la-plantilla-de-sunrise-medical-se-mantiene-en-huelga-ante-la-nula-voluntad-negociadora-de-la-direccion\/","title":{"rendered":"La plantilla de Sunrise Medical se mantiene en huelga ante la nula voluntad negociadora de la direcci\u00f3n"},"content":{"rendered":"<p> <\/p>\n<div style=\"padding-right:15px;width:345px; float:left; border-right-style:solid; border-right-width:1px; border-right-color:#dddddd\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-19074\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise.jpg\" width=\"345\" height=\"231\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise.jpg 1109w, https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise-300x200.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise-1024x684.jpg 1024w, https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise-768x513.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise-150x100.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise-696x465.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise-1068x714.jpg 1068w, https:\/\/www.lab.eus\/wp-content\/uploads\/2019\/03\/materiala_argazkiak_industria_metala_19_03_28Sunrise_Sunrise-629x420.jpg 629w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><em><span style=\"font-size: 14px; \"><\/p>\n<p> Sunrise Medical, empresa ubicada en el Poligono de Bakiola de Arrankudiaga y que fabrica sillas electricas y elementes de ortopedia, se encuentra de huelga desde el pasado dia 20 de marzo. La plantilla compuesta por 43 trabajadores y trabajadoras de produccion y otros tantos y tantas de oficinas inicio las negociaciones del Convenio de empresa el pasado septiembre. La postura de la empresa ha sido desde el primer momento de nula voluntad negociadora, neg&aacute;ndose en todo momento a hablar y dialogar sobre los puntos importantes de la plataforma que presentaron los y las trabajadoras de la f&aacute;brica.<\/p>\n<p> <\/span><\/em>La planta de Sunrise Medical de Bakiola sigue generando beneficios a&ntilde;o tras a&ntilde;o y aumentando su producctividad. Prueba de la excelente salud econ&oacute;mica de la planta es el reparto de altos dividendos entre sus accionistas y que la planta vasca sigue financiando  a otras plantas de la compa&ntilde;ia, sin dirigir sus inversiones a la planta de Bakiola.<\/p>\n<p> En contraste con esta realidad, la plantilla de Sunrise Medical se encuentra con unas condiciones laborales inaceptables a lo que se suman  aumentos de ritmo de trabajo. Recuperar el poder poder adquisitivo perdido los ultimos a&ntilde;os, que las bajas se complementen, que las categorias profesionales no se petrifiquen o que dejen de utilizarse las ETTs y la eventualidad para puestos de trabajo estructurales son algunas de las reivindicaciones de la plantilla que la empresa se niega a afrontar.<\/p>\n<p> La plantilla, con el apoyo de los dos delegados de ELA y el delegado de LAB, convoc&oacute; el pasado d&iacute;a 20 de marzo  huelga ante la nula voluntad negociadora de la direcci&oacute;n de la empresa. En asamblea, han ratificado su intenci&oacute;n de mantenerse firmes y el tiempo que sea necesario hasta la consecuci&oacute;n de sus reivindicaciones. Reivindicaciones que consideran m&aacute;s que justas y no entienden la cerraz&oacute;n de la empresa vista su situaci&oacute;n econ&oacute;mica y productiva.<\/p>\n<p> Anuncian pr&oacute;ximas movilizaciones para hacer saber a la opini&oacute;n p&uacute;blica y a los clientes de Sunrise Medical su situaci&oacute;n.<\/p>\n<p> &nbsp;<\/div>\n<div style=\"width:180px; float:left; padding-left:15px;\">\n<div style=\"text-align: center; \"><a href=\"\/rssak\"><input src=\"\/materiala\/argazkiak\/feed.png\" alt=\"RSSak\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.facebook.com\/pages\/LAB-sindikatua\/292846207397345\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/facebook.png\" alt=\"LAB Facebooken\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/issuu.com\/lab_argitalpenak\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/issuu.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/es.scribd.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/scribd.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><br \/> <\/a><\/div>\n<div style=\"text-align: center; \"><a target=\"_blank\" href=\"http:\/\/twitter.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/twitter.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/labsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/youtube.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/lab-sindikatua\/\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/flickr.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a href=\"http:\/\/www.labsindikatua.org\/eu\/hasiera\/upload\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/igo.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><\/div>\n<p> &nbsp;<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sunrise Medical, empresa ubicada en el Poligono de Bakiola de Arrankudiaga y que fabrica sillas electricas y elementes de ortopedia, se encuentra de huelga desde el pasado dia 20 de marzo. La plantilla compuesta por 43 trabajadores y trabajadoras de produccion y otros tantos y tantas de oficinas inicio las negociaciones del Convenio de empresa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[108],"tags":[2996,3064],"class_list":{"0":"post-19075","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-metal","8":"tag-industria-es","9":"tag-metal-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/19075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=19075"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/19075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/19074"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=19075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=19075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=19075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}