{"id":18365,"date":"2018-12-03T13:54:19","date_gmt":"2018-12-03T13:54:19","guid":{"rendered":"https:\/\/www.lab.eus\/el-gobierno-vasco-pretende-perpetuar-la-precariedad-y-la-temporalidad-en-la-administracion\/"},"modified":"2018-12-03T13:54:19","modified_gmt":"2018-12-03T13:54:19","slug":"el-gobierno-vasco-pretende-perpetuar-la-precariedad-y-la-temporalidad-en-la-administracion","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/el-gobierno-vasco-pretende-perpetuar-la-precariedad-y-la-temporalidad-en-la-administracion\/","title":{"rendered":"El Gobierno Vasco pretende perpetuar la precariedad y la temporalidad en la administraci\u00f3n"},"content":{"rendered":"<div style=\"padding-right:15px;width:345px; float:left; border-right-style:solid; border-right-width:1px; border-right-color:#dddddd\"><em><span style=\"font-size: 14px; \">Ayer el Gobierno anunciaba la apertura de bolsas de trabajo en la Administraci&oacute;n general, y como de costumbre, por medio de operaciones medi&aacute;ticas, estas bolsas se anunciaban como el resultado del compromiso con el empleo p&uacute;blico. Sin embargo, el sindicato LAB quiere denunciar la utilizaci&oacute;n mezquina que se est&aacute; haciendo de las bolsas de trabajo o de otros m&eacute;todos de la administraci&oacute;n, como las comisiones de servicios, con los que se est&aacute; profundizando, aun m&aacute;s, en el desgaste del empleo p&uacute;blico: fomentando la ya inadmisible tasa de temporalidad.<\/p>\n<p> <\/span><\/em>Adem&aacute;s, hemos de denunciar que las listas a las que se hace referencia son concretamente para cubrir llamamientos en el centro de menores de Zum&aacute;rraga, Ibaiondo, y para el EUSTAT, dos centros, donde precisamente, la temporalidad y la falta de compromisos serios se ha llevado hasta el extremo generando importantes conflictos laborales, a&uacute;n sin esclarecer. Por esta raz&oacute;n, nos parece aun m&aacute;s grave este hecho, cuando estamos en procesos de negociaci&oacute;n para dignificar las condiciones laborales de estos colectivos y poniendo en riesgo dichos procesos.<\/p>\n<p> Lo m&aacute;s grave es que, detr&aacute;s de esta operaci&oacute;n medi&aacute;tica, haya una intenci&oacute;n de tapar la grave situaci&oacute;n que durante a&ntilde;os hemos padecido en los colectivos m&aacute;s precarios de la administraci&oacute;n, ofertando m&aacute;s temporalidad y generando una mayor brecha y m&aacute;s conflictos en estos colectivos.<\/p>\n<p> Solicitamos, como hemos hecho hasta ahora, un plan de empleo para toda la administraci&oacute;n, d&oacute;nde se ponga fin a la intolerable tasas de interinidad, mediante procesos de consolidaci&oacute;n del empleo y ofertas p&uacute;blicas de empleo.<br \/> &nbsp;<\/div>\n<div style=\"width:180px; float:left; padding-left:15px;\">\n<div style=\"text-align: center; \"><a href=\"\/rssak\"><input src=\"\/materiala\/argazkiak\/feed.png\" alt=\"RSSak\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.facebook.com\/pages\/LAB-sindikatua\/292846207397345\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/facebook.png\" alt=\"LAB Facebooken\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/issuu.com\/lab_argitalpenak\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/issuu.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/es.scribd.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/scribd.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><br \/> <\/a><\/div>\n<div style=\"text-align: center; \"><a target=\"_blank\" href=\"http:\/\/twitter.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/twitter.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/labsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/youtube.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/lab-sindikatua\/\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/flickr.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a href=\"http:\/\/www.labsindikatua.org\/eu\/hasiera\/upload\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/igo.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><\/div>\n<p> &nbsp;<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ayer el Gobierno anunciaba la apertura de bolsas de trabajo en la Administraci&oacute;n general, y como de costumbre, por medio de operaciones medi&aacute;ticas, estas bolsas se anunciaban como el resultado del compromiso con el empleo p&uacute;blico. Sin embargo, el sindicato LAB quiere denunciar la utilizaci&oacute;n mezquina que se est&aacute; haciendo de las bolsas de trabajo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[76],"tags":[],"class_list":{"0":"post-18365","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-es-gobierno-vasco-es-servicios-publicos"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/18365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=18365"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/18365\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=18365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=18365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=18365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}