{"id":15883,"date":"2017-09-20T10:20:34","date_gmt":"2017-09-20T10:20:34","guid":{"rendered":"https:\/\/www.lab.eus\/denunciamos-la-muerte-de-un-trabajador-en-la-empresa-cables-y-alambres-del-grupo-vicinay-de-erandio\/"},"modified":"2017-09-20T10:20:34","modified_gmt":"2017-09-20T10:20:34","slug":"denunciamos-la-muerte-de-un-trabajador-en-la-empresa-cables-y-alambres-del-grupo-vicinay-de-erandio","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/denunciamos-la-muerte-de-un-trabajador-en-la-empresa-cables-y-alambres-del-grupo-vicinay-de-erandio\/","title":{"rendered":"Denunciamos la muerte de un trabajador en la empresa Cables y Alambres del grupo Vicinay de Erandio"},"content":{"rendered":"<p> <\/p>\n<div style=\"padding-right:15px;width:345px; float:left; border-right-style:solid; border-right-width:1px; border-right-color:#dddddd\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15881\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi1.jpg\" width=\"345\" height=\"128\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi1.jpg 800w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi1-300x111.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi1-768x284.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi1-150x56.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi1-696x258.jpg 696w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><em><span style=\"font-size: 14px; \"><\/p>\n<p> Hoy mie\u0301rcoles hemos tenido conocimiento de un nuevo accidente mortal en el que el operario ha fallecido tras ser atrapado por una ma\u0301quina. En primer lugar, queremos manifestar nuestra condolencia y apoyo a los familiares del trabajador fallecido, asimismo, nos solidarizamos con sus personas allegadas, compan\u0303eras y compan\u0303eros, asi\u0301 como con toda la clase trabajadora. Con este nuevo fallecimientos son al menos 43 los trabajadores y trabajadoras fallecidas en accidente de trabajo en lo que llevamos de 2017 en Euskal Herria.<\/p>\n<p> <\/span><\/em>Tenemos claro que los accidentes no son puntuales ni ocurren por casualidad, estamos ante un problema estructural, responden a un modelo de relaciones laborales en el que la salud y la vida de los y las trabajadoras esta\u0301n en peligro.<\/p>\n<p> Denunciamos que la precariedad mata, que hay responsables y que los accidentes se pueden y se tienen que evitar. Este accidente laboral tiene unos responsables concretos, la empresa Cables y Alambres Especiales y el Grupo Vicinay.<\/p>\n<p> En esta empresa hemos realizado denuncias y paralizado ma\u0301quinas en diferentes ocasiones y ante esto, la respuesta de la empresa ha sido ejercer presio\u0301n sobre la representacio\u0301n de las y los trabajadores y no tomar las debidas medidas preventivas que eviten accidentes. Una empresa donde no se realiza inversio\u0301n alguna y las ma\u0301quinas esta\u0301n obsoletas y anticuadas.<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15882\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi2.jpg\" width=\"345\" height=\"194\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi2.jpg 800w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi2-300x169.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi2-768x432.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi2-150x84.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi2-696x392.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/09\/materiala_argazkiak_Arloak_lanOsasuna_17_09_20Erandio_Xabi2-747x420.jpg 747w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><\/p>\n<p> La falta de inversio\u0301n desde hace de\u0301cadas ha conducido al deterioro ma\u0301ximo de las maquinas y las instalaciones y en consecuencia, a que los trabajadores y trabajadoras hayan tenido que acudir al puesto de trabajo juga\u0301ndose la vida a diario, a que los accidentes laborales hayan sido una constante a lo largo de los u\u0301ltimos an\u0303os.<\/p>\n<p> El grupo Vicinay adquirio\u0301 la empresa Cables y Alambres en mayo del an\u0303o 2015, prometiendo una serie de inversiones que nunca han llegado.<\/p>\n<p> El sindicato LAB viene denunciando las condiciones infrahumanas en las que las y los trabajadores veni\u0301an realizando su trabajo y que ante esto, la respuesta de la empresa ha sido represio\u0301n, presio\u0301n e imposicio\u0301n de ritmos de trabajo inasumibles.<\/p>\n<p> Nuevamente exigimos a las autoridades tolerancia cero, control y vigilancia.<\/p>\n<p> Por u\u0301ltimo, desde el sindicato LAB llamamos a participar en la respuesta que en las pro\u0301ximas horas se puedan articular, y a luchar en los centros de trabajo por unas condiciones de trabajo dignas y un modelo en el que por encima de los beneficios empresariales prime la salud de los trabajadores y trabajadoras.<\/p>\n<p> La precariedad asesina y hay responsables.<\/p>\n<p> Convocada por su comit&eacute; de empresa, la plantilla de Cables y Alambres se concentrar&aacute; ante la empresa en denuncia de la muerte de su compa&ntilde;ero en accidente laboral. Ser&aacute; ma&ntilde;ana, a las 12:00, frente a la empresa de Erandio.<\/p>\n<p> &nbsp;<\/div>\n<div style=\"width:180px; float:left; padding-left:15px;\">\n<div style=\"text-align: center; \"><a href=\"\/rssak\"><input src=\"\/materiala\/argazkiak\/feed.png\" alt=\"RSSak\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.facebook.com\/pages\/LAB-sindikatua\/292846207397345\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/facebook.png\" alt=\"LAB Facebooken\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/issuu.com\/lab_argitalpenak\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/issuu.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/es.scribd.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/scribd.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><br \/> <\/a><\/div>\n<div style=\"text-align: center; \"><a target=\"_blank\" href=\"http:\/\/twitter.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/twitter.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/labsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/youtube.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/lab-sindikatua\/\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/flickr.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a href=\"http:\/\/www.labsindikatua.org\/eu\/hasiera\/upload\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/igo.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><\/div>\n<p> &nbsp;<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hoy mie\u0301rcoles hemos tenido conocimiento de un nuevo accidente mortal en el que el operario ha fallecido tras ser atrapado por una ma\u0301quina. En primer lugar, queremos manifestar nuestra condolencia y apoyo a los familiares del trabajador fallecido, asimismo, nos solidarizamos con sus personas allegadas, compan\u0303eras y compan\u0303eros, asi\u0301 como con toda la clase trabajadora. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[130],"tags":[],"class_list":{"0":"post-15883","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-es-la-precariedad-mata-es-salud-laboral"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/15883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=15883"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/15883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/15881"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=15883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=15883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=15883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}