{"id":14916,"date":"2017-02-03T10:30:25","date_gmt":"2017-02-03T10:30:25","guid":{"rendered":"https:\/\/www.lab.eus\/ainhoa-etxaide-las-personas-han-de-estar-en-el-centro-de-la-politica-no-el-mercado\/"},"modified":"2017-02-03T10:30:25","modified_gmt":"2017-02-03T10:30:25","slug":"ainhoa-etxaide-las-personas-han-de-estar-en-el-centro-de-la-politica-no-el-mercado","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/ainhoa-etxaide-las-personas-han-de-estar-en-el-centro-de-la-politica-no-el-mercado\/","title":{"rendered":"Ainhoa Etxaide: \u00abLas personas han de estar en el centro de la pol\u00edtica, no el mercado\u00bb"},"content":{"rendered":"<p> <\/p>\n<div style=\"padding-right:15px;width:345px; float:left; border-right-style:solid; border-right-width:1px; border-right-color:#dddddd\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14914\" width=\"345\" height=\"145\" alt=\"\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Manifestazioa1.JPG\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Manifestazioa1.JPG 800w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Manifestazioa1-300x126.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Manifestazioa1-768x324.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Manifestazioa1-150x63.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Manifestazioa1-696x293.jpg 696w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><em><span style=\"font-size: 14px; \"><\/p>\n<p> Representantes de sindicatos y agentes sociales han realizado hoy una cadena humana en Bilbo, a llamamiento de la Carta de Derechos Sociales de Euskal Herria. Los manifestantes han recorrido el trayecto que va desde la sede de Lanbide hasta la delegaci&oacute;n del Gobierno Vasco. Han denunciado los recortes y han reivindicado que se aplique a la Renta de Garant&iacute;a de Ingresos (RGI) la misma subida que al Salario M&iacute;nimo Interprofesional (SMI). &quot;Queremos que se respete y se mejore el RGI, derecho adquirido despu&eacute;s de la lucha llevada a cabo en Euskal Herria&quot;, ha se&ntilde;alado la secretaria general de LAB.<\/p>\n<p> <\/span><\/em>La secretaria general de LAB, Ainhoa Etxaide, ha pedido a los partidos que forman el Gobierno Vasco que cambien su pol&iacute;tica social: &quot;Cuando terminan las elecciones, cuando se dejan a un lado los discursos, cuando llega el momento de materializar pol&iacute;ticas, lo primero que demuestra un gobierno es a quien va a proteger y cuidar. Y el Gobierno Vasco, PNV y PSE-EE, han vuelto a demostrar que solo van a proteger al mercado, y no a las personas. En este sentido, LAB tiene muy clara su posici&oacute;n: &quot;Las personas han de estar en el centro de las pol&iacute;ticas, no el mercado&quot;, ha indicado la secretaria general del sindicato.<\/p>\n<p> Ha remarcado que la precariedad no se limita &uacute;nicamente a las pobres condiciones laborales que padecen las y los trabajadores: &quot;La precariedad es un sistema que deja desprotegidas a las y los trabajadores, les deja sin derechos, sin prestaciones, en manos del mercado y de los empresarios. Eso trae pobreza, precariedad y desigualdad social&quot;, ha explicado Etxaide.<\/p>\n<p> <em><span style=\"font-size: 14px; \"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14915\" width=\"345\" height=\"224\" alt=\"\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Mnaifestazioa2.JPG\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Mnaifestazioa2.JPG 800w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Mnaifestazioa2-300x195.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Mnaifestazioa2-768x498.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Mnaifestazioa2-150x97.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Mnaifestazioa2-696x452.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2017\/02\/materiala_argazkiak_euskalHerria_EskubideSozialenKarta_17_02_03Gizakatea_Mnaifestazioa2-647x420.jpg 647w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><\/span><\/em><\/p>\n<p> El sindicato tiene muy claro c&oacute;mo hacer frente a la situaci&oacute;n: &quot;Si comparamos el periodo comprendido entre 2008 y 2014, las desigualdades han incrementado entre los que tienen y no tienen. Esa situaci&oacute;n se afronta con pol&iacute;ticas sociales, protecci&oacute;n social y prestaciones sociales. Por ello, pedimos al Gobierno Vasco que luche contra la pobreza, teniendo en cuenta que existen medidas para hacerlo. Le pedimos que aplique esas medidas&quot;, ha a&ntilde;adido Etxaide.<br \/> &nbsp;<\/div>\n<div style=\"width:180px; float:left; padding-left:15px;\">\n<div style=\"text-align: center; \"><a href=\"\/rssak\"><input src=\"\/materiala\/argazkiak\/feed.png\" alt=\"RSSak\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.facebook.com\/pages\/LAB-sindikatua\/292846207397345\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/facebook.png\" alt=\"LAB Facebooken\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/issuu.com\/lab_argitalpenak\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/issuu.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/es.scribd.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/scribd.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><br \/> <\/a><\/div>\n<div style=\"text-align: center; \"><a target=\"_blank\" href=\"http:\/\/twitter.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/twitter.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/labsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/youtube.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/lab-sindikatua\/\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/flickr.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a href=\"http:\/\/www.labsindikatua.org\/eu\/hasiera\/upload\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/igo.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><\/div>\n<p> &nbsp;<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Representantes de sindicatos y agentes sociales han realizado hoy una cadena humana en Bilbo, a llamamiento de la Carta de Derechos Sociales de Euskal Herria. Los manifestantes han recorrido el trayecto que va desde la sede de Lanbide hasta la delegaci&oacute;n del Gobierno Vasco. Han denunciado los recortes y han reivindicado que se aplique a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3339,2998],"tags":[],"class_list":{"0":"post-14916","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-carta-de-derechos-sociales","8":"category-uncategorized-eu-es"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/14916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=14916"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/14916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/14914"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=14916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=14916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=14916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}