{"id":14913,"date":"2017-02-02T16:15:35","date_gmt":"2017-02-02T16:15:35","guid":{"rendered":"https:\/\/www.lab.eus\/es-urgente-combatir-un-modelo-que-no-contempla-el-empleo-como-prioridad\/"},"modified":"2017-02-02T16:15:35","modified_gmt":"2017-02-02T16:15:35","slug":"es-urgente-combatir-un-modelo-que-no-contempla-el-empleo-como-prioridad","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/es-urgente-combatir-un-modelo-que-no-contempla-el-empleo-como-prioridad\/","title":{"rendered":"Es urgente combatir un modelo que no contempla el empleo como prioridad"},"content":{"rendered":"<p> <\/p>\n<div style=\"padding-right:15px;width:345px; float:left; border-right-style:solid; border-right-width:1px; border-right-color:#dddddd\"><em><span style=\"font-size: 14px; \">Han dado hoy a conocer los datos del paro relativos al mes de enero. En la actualidad, hay un total de 180.319 personas desempleadas e inscritas en las oficinas que los servicios p&uacute;blicos de empleo tienen repartidas por Hego Euskal Herria. El final de la campa&ntilde;a navide&ntilde;a y las rebajas han impulsado al alza la cifra oficial de paro en enero, registrando 4.101 personas m&aacute;s desempleadas con respecto al mes anterior.<\/p>\n<p> <\/span><\/em>La evoluci&oacute;n del paro registrado no proporciona una medida ajustada del volumen real de empleo que se ha perdido en el &uacute;ltimo mes. En concreto, la informaci&oacute;n de la Seguridad Social revela que la afiliaci&oacute;n al instituto p&uacute;blico se ha reducido en 12.500 personas, lo que supone una destrucci&oacute;n de empleo significativamente superior a la que cabr&iacute;a deducir de los datos de paro registrado.<\/p>\n<p> Este hecho pone de manifiesto una vez m&aacute;s que gran parte de los nuevos empleos son precarios e inestables, y por lo tanto muy fr&aacute;giles. De ah&iacute; que sea tan importante volver a recordar que en materia de creaci&oacute;n de empleo la cantidad es importante, pero la calidad es fundamental.<\/p>\n<p> Evidentemente, la mala calidad del empleo tiene responsables pol&iacute;ticos y econ&oacute;micos, pero sobre todo, dice mucho acerca de la &ldquo;calidad&rdquo; de la patronal y de su modelo empresarial.<\/p>\n<p> Por ello consideramos que ante la actual crisis de precariedad es urgente concentrar todos los esfuerzos en combatir un modelo socioecon&oacute;mico que no contempla el empleo como una prioridad, y sin embargo, valora la precariedad como una f&oacute;rmula de inserci&oacute;n laboral inevitable.<br \/> &nbsp;<\/div>\n<div style=\"width:180px; float:left; padding-left:15px;\">\n<div style=\"text-align: center; \"><a href=\"\/rssak\"><input src=\"\/materiala\/argazkiak\/feed.png\" alt=\"RSSak\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.facebook.com\/pages\/LAB-sindikatua\/292846207397345\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/facebook.png\" alt=\"LAB Facebooken\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/issuu.com\/lab_argitalpenak\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/issuu.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/es.scribd.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/scribd.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><br \/> <\/a><\/div>\n<div style=\"text-align: center; \"><a target=\"_blank\" href=\"http:\/\/twitter.com\/LABsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/twitter.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/labsindikatua\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/youtube.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/lab-sindikatua\/\" rel=\"noopener noreferrer\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/flickr.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><a href=\"http:\/\/www.labsindikatua.org\/eu\/hasiera\/upload\"><input src=\"\/modules\/mod_socialmediacloud\/icons\/igo.png\" longdesc=\"undefined\" width=\"30\" type=\"image\" height=\"30\" \/><\/a><\/div>\n<p> &nbsp;<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Han dado hoy a conocer los datos del paro relativos al mes de enero. En la actualidad, hay un total de 180.319 personas desempleadas e inscritas en las oficinas que los servicios p&uacute;blicos de empleo tienen repartidas por Hego Euskal Herria. El final de la campa&ntilde;a navide&ntilde;a y las rebajas han impulsado al alza la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2994],"tags":[3182,3101],"class_list":{"0":"post-14913","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-accion-social","7":"tag-accion-social-es","8":"tag-desempleo"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/14913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=14913"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/14913\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=14913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=14913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=14913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}