{"id":10442,"date":"2012-07-13T11:13:26","date_gmt":"2012-07-13T11:13:26","guid":{"rendered":"https:\/\/www.lab.eus\/tav-el-incumplimiento-del-convenio-provoca-muertes-y-genera-pobreza\/"},"modified":"2012-07-13T11:13:26","modified_gmt":"2012-07-13T11:13:26","slug":"tav-el-incumplimiento-del-convenio-provoca-muertes-y-genera-pobreza","status":"publish","type":"post","link":"https:\/\/www.lab.eus\/es\/tav-el-incumplimiento-del-convenio-provoca-muertes-y-genera-pobreza\/","title":{"rendered":"TAV: El incumplimiento del Convenio provoca muertes y genera pobreza"},"content":{"rendered":"<p>ELA, LAB, STEE-EILAS, EHNE e HIRU convocan una concentraci&oacute;n el pr&oacute;ximo lunes 16 en Arrasate para denunciar la &uacute;ltima muerte obrera.<br \/>  <!--more--> <br \/> Ayer 12 de julio, el trabajador A.A.R de 55 a&ntilde;os de edad de la empresa TIERRA ARMADA DE PREFABRICADOS, subcontratada por la UTE AVE Mondragon formada AMENABAR y SACYR-VALLEHERMOSO, sufrio un accidente laboral mortal, al ser aplastado por una pieza de hormigon durante el transcurso de unos trabajos de colocaci&oacute;n de prefabricados.<\/p>\n<p> Desde el sindicato LAB queremos mostrar nuestro apoyo y solidaridad con sus familiares, allegados y la clase trabajadora. <\/p>\n<p> El los &uacute;ltimos a&ntilde;os 6 trabajadores han fallecido en los obras de construcci&oacute;n del tren de Alta Velocidad (TAV): El primero de ellos el 14 de julio de 2008 en Luku; en el 2010, en el accidente producido en Durana el 11 de agosto y el producido en Eskoriatza el 9 de diciembre; en 2011 el producido en Antzuola el 8 de marzo y en el accidente producido en Tolosa el 6 de septiembre y el &uacute;ltimo, este a&ntilde;o 2012, el ocurrido ayer en Arrasate. A ellos hay que sumar los incalculables accidentes leves y graves y las enfermedades de origen laboral, que a pesar de ocultarse ocurren en las obras de construcci&oacute;n del TAV.<\/p>\n<p> Como siempre hemos denunciado sindicalmente todas las perdidas de salud tienen su origen principal en las condiciones de trabajo, es la precariedad, la subcontrataci&oacute;n en cadena, la temporalidad, etc. las que se sit&uacute;an en la base de la pir&aacute;mide de accidentes y enfermedades. Y esto es mas claro, cuando en estas obras se incumple sistem&aacute;ticamente la aplicaci&oacute;n del convenio sectorial provincial de construcci&oacute;n. De esta forma se abre la puerta a incumplimientos generalizados y a la precarizaci&oacute;n galopante de las condiciones de trabajo y vida en las obras del TAV, y una de sus consecuencias mas directas son todas las perdidas de salud y vida que se estan produciendo en las obras del TAV.<\/p>\n<p> Desde LAB queremos denunciar como nos imponen unas obras fara&oacute;nicas que solo interesan a las &ldquo;elites&rdquo; econ&oacute;micas y pol&iacute;ticas, para seguir manteniendo y aumentando sus beneficios, mientras entre las personas trabajadoras genera pobreza. Siendo encima unas infraestructuras que destruyen el medio ambiente, desequilibran el territorio y adem&aacute;s son obras asesinas que se cobran la vida de trabajadores. Exigimos la paralizaci&oacute;n de estas obras.<\/p>\n<p> En un momento en el que se reduce a la m&iacute;nima expresi&oacute;n el gasto publico, en el que los apologetas del sistema dicen que la situaci&oacute;n exige &ldquo;responsabilidad y austeridad&rdquo;. Las obras del TAV ya han dicho por activa y por pasiva que son obras que se van a llevar adelante, cueste lo que cueste (mucho mas de lo presupuestado) y en el tiempo se&ntilde;alado, lo importante es el negocio.<\/p>\n<p> Las administraciones publicas cuando act&uacute;an como patronal, siguen las mismas recetas neoliberales de hacer mas en el menor tiempo y con el menor costo posible. Los plazos de las obras se reducen, as&iacute; que aumentan las prisas y los ritmos de trabajo, las horas extras; La subcontrataci&oacute;n en cadena se convierte en norma al igual que la temporalidad, no se aplica el convenio correspondiente, etc. En definitiva en teor&iacute;a estos te&oacute;ricos garantes de nuestros derechos precarizan el mercado de trabajo, aun sabiendo que con mayor precariedad mayor numero de accidentes, pero nuestra salud y nuestra vida no les importa.<\/p>\n<p> El cambio esta en la movilizaci&oacute;n y en la lucha, para ello el lunes 16 de abril desde los sindicatos ELA, LAB, HIRU, EHNE y STEE-EILAS nos vamos a concentrar en la Plaza de Arrasate a las 11,30 horas como repulsa ante esta situaci&oacute;n de p&eacute;rdidas de salud y muertes obreras, porque:<\/p>\n<p> <strong>&iexcl;EL TAV PERJUDICA SERIAMENTE NUESTRA SALUD!<br \/> <\/strong><br \/> <strong>LAN ISTRIPU GEHIAGORIK EZ! &nbsp;PREKARIETATEA HILTZAILEA.<br \/> <\/strong> <\/p>\n<div style=\"text-align: right; \"><strong>Euskal Herria, 13 de julio de 2012<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ELA, LAB, STEE-EILAS, EHNE e HIRU convocan una concentraci&oacute;n el pr&oacute;ximo lunes 16 en Arrasate para denunciar la &uacute;ltima muerte obrera.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[130],"tags":[],"class_list":{"0":"post-10442","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-es-la-precariedad-mata-es-salud-laboral"},"_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/10442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=10442"}],"version-history":[{"count":0,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/posts\/10442\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media?parent=10442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/categories?post=10442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/tags?post=10442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}