{"id":90234,"date":"2026-03-17T20:07:42","date_gmt":"2026-03-17T20:07:42","guid":{"rendered":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1.jpg"},"modified":"2026-03-17T20:07:42","modified_gmt":"2026-03-17T20:07:42","slug":"bermeo-1-2","status":"inherit","type":"attachment","link":"https:\/\/www.lab.eus\/es\/argazki-galeria-arratsaldeko-mobilizazioak\/bermeo-1-2\/","title":{"rendered":"Bermeo 1"},"author":1191,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_links_to":"","_links_to_target":""},"class_list":["post-90234","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"287\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-300x287.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-300x287.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1024x981.jpg 1024w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-768x735.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1536x1471.jpg 1536w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-439x420.jpg 439w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-150x144.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-696x666.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1068x1023.jpg 1068w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1920x1838.jpg 1920w, https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1961,"file":"2026\/03\/Bermeo-1-1.jpg","filesize":701249,"sizes":{"medium":{"file":"Bermeo-1-1-300x287.jpg","width":300,"height":287,"filesize":27091,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-300x287.jpg"},"large":{"file":"Bermeo-1-1-1024x981.jpg","width":1024,"height":981,"filesize":238450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1024x981.jpg"},"thumbnail":{"file":"Bermeo-1-1-150x150.jpg","width":150,"height":150,"filesize":8447,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-150x150.jpg"},"medium_large":{"file":"Bermeo-1-1-768x735.jpg","width":768,"height":735,"filesize":143074,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-768x735.jpg"},"1536x1536":{"file":"Bermeo-1-1-1536x1471.jpg","width":1536,"height":1471,"filesize":494851,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1536x1471.jpg"},"td_0x420":{"file":"Bermeo-1-1-439x420.jpg","width":439,"height":420,"filesize":53842,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-439x420.jpg"},"td_80x60":{"file":"Bermeo-1-1-80x60.jpg","width":80,"height":60,"filesize":2369,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-80x60.jpg"},"td_150x0":{"file":"Bermeo-1-1-150x144.jpg","width":150,"height":144,"filesize":8085,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-150x144.jpg"},"td_218x150":{"file":"Bermeo-1-1-218x150.jpg","width":218,"height":150,"filesize":11861,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-218x150.jpg"},"td_300x0":{"file":"Bermeo-1-1-300x287.jpg","width":300,"height":287,"filesize":27066,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-300x287.jpg"},"td_324x400":{"file":"Bermeo-1-1-324x400.jpg","width":324,"height":400,"filesize":39094,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-324x400.jpg"},"td_485x360":{"file":"Bermeo-1-1-485x360.jpg","width":485,"height":360,"filesize":53424,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-485x360.jpg"},"td_696x0":{"file":"Bermeo-1-1-696x666.jpg","width":696,"height":666,"filesize":121133,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-696x666.jpg"},"td_1068x0":{"file":"Bermeo-1-1-1068x1023.jpg","width":1068,"height":1023,"filesize":259604,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1068x1023.jpg"},"td_1920x0":{"file":"Bermeo-1-1-1920x1838.jpg","width":1920,"height":1838,"filesize":727478,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1-1920x1838.jpg"},"full":{"file":"Bermeo-1-1.jpg","width":2048,"height":1961,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":89839,"source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2026\/03\/Bermeo-1-1.jpg","_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/90234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=90234"}]}}