{"id":81420,"date":"2025-06-11T11:38:10","date_gmt":"2025-06-11T11:38:10","guid":{"rendered":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288.jpg"},"modified":"2025-06-11T11:38:10","modified_gmt":"2025-06-11T11:38:10","slug":"img_6288","status":"inherit","type":"attachment","link":"https:\/\/www.lab.eus\/es\/lab-pide-compromisos-reales-y-voluntad-politica-a-las-administraciones-para-que-el-cuidado-deje-de-ser-un-negocio\/img_6288\/","title":{"rendered":"IMG_6288"},"author":1191,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_links_to":"","_links_to_target":""},"class_list":["post-81420","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-300x200.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1024x683.jpg 1024w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-768x512.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1536x1024.jpg 1536w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-2048x1365.jpg 2048w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-630x420.jpg 630w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-150x100.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-696x464.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1068x712.jpg 1068w, https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2025\/06\/IMG_6288-scaled.jpg","filesize":546181,"sizes":{"medium":{"file":"IMG_6288-300x200.jpg","width":300,"height":200,"filesize":50534,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-300x200.jpg"},"large":{"file":"IMG_6288-1024x683.jpg","width":1024,"height":683,"filesize":148686,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1024x683.jpg"},"thumbnail":{"file":"IMG_6288-150x150.jpg","width":150,"height":150,"filesize":42709,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-150x150.jpg"},"medium_large":{"file":"IMG_6288-768x512.jpg","width":768,"height":512,"filesize":105547,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-768x512.jpg"},"1536x1536":{"file":"IMG_6288-1536x1024.jpg","width":1536,"height":1024,"filesize":254770,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1536x1024.jpg"},"2048x2048":{"file":"IMG_6288-2048x1365.jpg","width":2048,"height":1365,"filesize":388962,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-2048x1365.jpg"},"td_0x420":{"file":"IMG_6288-630x420.jpg","width":630,"height":420,"filesize":86433,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-630x420.jpg"},"td_80x60":{"file":"IMG_6288-80x60.jpg","width":80,"height":60,"filesize":38061,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-80x60.jpg"},"td_150x0":{"file":"IMG_6288-150x100.jpg","width":150,"height":100,"filesize":40785,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-150x100.jpg"},"td_218x150":{"file":"IMG_6288-218x150.jpg","width":218,"height":150,"filesize":44882,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-218x150.jpg"},"td_300x0":{"file":"IMG_6288-300x200.jpg","width":300,"height":200,"filesize":50534,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-300x200.jpg"},"td_324x400":{"file":"IMG_6288-324x400.jpg","width":324,"height":400,"filesize":65661,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-324x400.jpg"},"td_485x360":{"file":"IMG_6288-485x360.jpg","width":485,"height":360,"filesize":71750,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-485x360.jpg"},"td_696x0":{"file":"IMG_6288-696x464.jpg","width":696,"height":464,"filesize":95228,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-696x464.jpg"},"td_1068x0":{"file":"IMG_6288-1068x712.jpg","width":1068,"height":712,"filesize":156639,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1068x712.jpg"},"td_1920x0":{"file":"IMG_6288-1920x1280.jpg","width":1920,"height":1280,"filesize":353085,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-1920x1280.jpg"},"td_1920x0_retina":{"file":"IMG_6288-3840x2560.jpg","width":3840,"height":2560,"filesize":1028666,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-3840x2560.jpg"},"full":{"file":"IMG_6288-scaled.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-scaled.jpg"}},"image_meta":{"aperture":"6.3","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1749641923","copyright":"","focal_length":"32","iso":"250","shutter_speed":"0.0015625","title":"","orientation":"1","keywords":[]},"original_image":"IMG_6288.jpg"},"post":81385,"source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2025\/06\/IMG_6288-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/81420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=81420"}]}}