{"id":76250,"date":"2024-12-04T16:16:13","date_gmt":"2024-12-04T16:16:13","guid":{"rendered":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y.jpg"},"modified":"2024-12-04T16:22:36","modified_gmt":"2024-12-04T16:22:36","slug":"photo_5940286069742355657_y-2","status":"inherit","type":"attachment","link":"https:\/\/www.lab.eus\/es\/hemos-ofrecido-formacion-en-derechos-laborales-y-organizacion-colectiva-a-casi-un-centenar-de-trabajadores-y-trabajadoras-migradas-y-racializadas\/photo_5940286069742355657_y-2\/","title":{"rendered":"photo_5940286069742355657_y"},"author":1191,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_links_to":"","_links_to_target":""},"class_list":["post-76250","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-300x203.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-768x521.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-150x102.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-696x472.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y.jpg 860w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":860,"height":583,"file":"2024\/12\/photo_5940286069742355657_y.jpg","filesize":112432,"sizes":{"medium":{"file":"photo_5940286069742355657_y-300x203.jpg","width":300,"height":203,"filesize":16220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-300x203.jpg"},"thumbnail":{"file":"photo_5940286069742355657_y-150x150.jpg","width":150,"height":150,"filesize":8604,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-150x150.jpg"},"medium_large":{"file":"photo_5940286069742355657_y-768x521.jpg","width":768,"height":521,"filesize":63477,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-768x521.jpg"},"td_150x0":{"file":"photo_5940286069742355657_y-150x102.jpg","width":150,"height":102,"filesize":7189,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-150x102.jpg"},"td_218x150":{"file":"photo_5940286069742355657_y-218x150.jpg","width":218,"height":150,"filesize":10942,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-218x150.jpg"},"td_300x0":{"file":"photo_5940286069742355657_y-300x203.jpg","width":300,"height":203,"filesize":16221,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-300x203.jpg"},"td_324x400":{"file":"photo_5940286069742355657_y-324x400.jpg","width":324,"height":400,"filesize":25996,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-324x400.jpg"},"td_485x360":{"file":"photo_5940286069742355657_y-485x360.jpg","width":485,"height":360,"filesize":34806,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-485x360.jpg"},"td_696x0":{"file":"photo_5940286069742355657_y-696x472.jpg","width":696,"height":472,"filesize":54627,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y-696x472.jpg"},"full":{"file":"photo_5940286069742355657_y.jpg","width":860,"height":583,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":76258,"source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2024\/12\/photo_5940286069742355657_y.jpg","_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/76250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=76250"}]}}