{"id":52835,"date":"2022-11-18T12:14:44","date_gmt":"2022-11-18T12:14:44","guid":{"rendered":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio.jpg"},"modified":"2022-11-18T12:14:44","modified_gmt":"2022-11-18T12:14:44","slug":"pentsio-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.lab.eus\/es\/pentsio-2-2\/","title":{"rendered":"Pentsio"},"author":1189,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_links_to":"","_links_to_target":""},"class_list":["post-52835","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-300x225.jpg 300w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1024x768.jpg 1024w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-768x576.jpg 768w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1536x1152.jpg 1536w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-150x113.jpg 150w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-696x522.jpg 696w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1068x801.jpg 1068w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1920x1440.jpg 1920w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-560x420.jpg 560w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-80x60.jpg 80w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-265x198.jpg 265w, https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":1500,"file":"2022\/11\/Pentsio.jpg","sizes":{"medium":{"file":"Pentsio-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-300x225.jpg"},"large":{"file":"Pentsio-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1024x768.jpg"},"thumbnail":{"file":"Pentsio-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-150x150.jpg"},"medium_large":{"file":"Pentsio-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-768x576.jpg"},"1536x1536":{"file":"Pentsio-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1536x1152.jpg"},"td_150x0":{"file":"Pentsio-150x113.jpg","width":150,"height":113,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-150x113.jpg"},"td_218x150":{"file":"Pentsio-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-218x150.jpg"},"td_300x0":{"file":"Pentsio-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-300x225.jpg"},"td_324x400":{"file":"Pentsio-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-324x400.jpg"},"td_485x360":{"file":"Pentsio-485x360.jpg","width":485,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-485x360.jpg"},"td_696x0":{"file":"Pentsio-696x522.jpg","width":696,"height":522,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-696x522.jpg"},"td_1068x0":{"file":"Pentsio-1068x801.jpg","width":1068,"height":801,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1068x801.jpg"},"td_1920x0":{"file":"Pentsio-1920x1440.jpg","width":1920,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1920x1440.jpg"},"td_0x420":{"file":"Pentsio-560x420.jpg","width":560,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-560x420.jpg"},"td_80x60":{"file":"Pentsio-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-80x60.jpg"},"td_100x70":{"file":"Pentsio-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-100x70.jpg"},"td_265x198":{"file":"Pentsio-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-265x198.jpg"},"td_324x160":{"file":"Pentsio-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-324x160.jpg"},"td_324x235":{"file":"Pentsio-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-324x235.jpg"},"td_356x220":{"file":"Pentsio-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-356x220.jpg"},"td_356x364":{"file":"Pentsio-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-356x364.jpg"},"td_533x261":{"file":"Pentsio-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-533x261.jpg"},"td_534x462":{"file":"Pentsio-534x462.jpg","width":534,"height":462,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-534x462.jpg"},"td_696x385":{"file":"Pentsio-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-696x385.jpg"},"td_741x486":{"file":"Pentsio-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-741x486.jpg"},"td_1068x580":{"file":"Pentsio-1068x580.jpg","width":1068,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio-1068x580.jpg"},"full":{"file":"Pentsio.jpg","width":2000,"height":1500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.lab.eus\/wp-content\/uploads\/2022\/11\/Pentsio.jpg","_links":{"self":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media\/52835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/users\/1189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lab.eus\/es\/wp-json\/wp\/v2\/comments?post=52835"}]}}